{"text_format":"1","workbook":"xlsx","n_sheets":16,"sheets":["Accueil","Infos_Recuperation","AOP22 - 035","Journalier","JANVIER","FEVRIER","MARS","AVRIL","MAI","JUIN","JUILLET","AOUT","SEPTEMBRE","OCTOBRE","NOVEMBRE","DECEMBRE"],"not_rendered":{"charts":0,"images":5,"macros":1,"external_links":2,"defined_names":503,"comments":0,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Accueil","index":0,"n_rows":0,"n_cols":0,"rows_kept":0,"cut":false,"hidden":false,"merged":[]}

{"sheet":"Infos_Recuperation","index":1,"n_rows":5,"n_cols":11,"rows_kept":5,"cut":false,"hidden":false,"merged":[]}
[]
[null,"CAJournalier_35_210322114128597.xls",null,null,null,"Niv 1 : 120 - COURRIER ET EXPEDITION",null,null,126.95,null,54.180000000100002]
[null,"CAJournalier_35_210322114255636.xls",null,null,null,"Niv 1 : 125 - CAHIERS ET DERIVES DE PAPIER",null,null,159.15,null,68.454999999899997]
[null,"CAJournalier_35_210322114306080.xls",null,null,null,"Niv 1 : 130 - ECRIRE ET CORRIGER",null,null,35.299999999999997,null,15.971666666300001]
[null,"CAJournalier_35_210322114313728.xls",null,null,null,"Niv 1 : 140 - CLASSEMENT",null,null,324.66000000000003,null,164.55083333370001]

{"sheet":"AOP22 - 035","index":2,"n_rows":39,"n_cols":27,"rows_kept":39,"cut":false,"hidden":false,"merged":[]}
[]
[2022]
[null,"Janvier","%","Février","%","Mars","%","Avril","%","Mai","%","Juin","%","Juillet","%","Août","%","Septembre","%","Octobre","%","Novembre","%","Décembre","%","Total YTD","%"]
["CA - Mo"]
[]
["CA - B"]
[]
["CA - F"]
[]
["CA - Mi"]
[]
["CA - C"]
[]
["Total CA"]
[]
[]
[]
[null,"Janvier","Taux %","Février","Taux %","Mars","Taux %","Avril","Taux %","Mai","Taux %","Juin","Taux %","Juillet","Taux %","Août","Taux %","Septembre","Taux %","Octobre","Taux %","Novembre","Taux %","Décembre","Taux %","Total YTD","Taux %"]
["Marge - Mo"]
[]
["Marge - B"]
[]
["Marge - F"]
[]
["Marge - Mi"]
[]
["Marge - C"]
[]
["Total MARGE"]
[]
[]
[]
[null,"Janvier","%/CA","Février","%/CA","Mars","%/CA","Avril","%/CA","Mai","%/CA","Juin","%/CA","Juillet","%/CA","Août","%/CA","Septembre","%/CA","Octobre","%/CA","Novembre","%/CA","Décembre","%/CA","Total YTD","%/CA"]
["COGS - Mo"]
["COGS - B"]
["COGS - F"]
["COGS - Mi"]
["COGS - C"]
["Total "]

{"sheet":"Journalier","index":3,"n_rows":47,"n_cols":12,"rows_kept":47,"cut":false,"hidden":false,"merged":[[42,11,43,11],[46,1,46,11],[42,0,43,0],[42,1,42,2],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10]]}
["Familles & sous familles","CA","Marge"]
["Niv 1 : 1 - MOBILIER        "]
["Niv 1 : 160 - EQUIPEMENT CLASSE ET BUREAU"]
["Niv 1 : 170 - MOBILIER"]
["Niv 1 : 200 - SERVICES GENERAUX"]
["Niv 1 : 205 - PRODUITS ALIMENTAIRES"]
["Niv 1 : 260 - UNIVERS MAGASIN"]
["MOBILIER",{"$f":"SUM(B2:B7)","v":0},{"$f":"SUM(C2:C7)","v":0}]
[null,null,null,87]
["Niv 1 : 2 - BUREAUTIQUE"]
["Niv 1 : 180 - BUREAUTIQUE"]
["Niv 1 : 195 - CONSOMMABLES INFORMATIQUES"]
["Niv 1 : 999 - NEW ITEMS RMS RECLASSIFY!"]
[" BUREAUTIQUE",{"$f":"SUM(B9:B13)","v":0},{"$f":"SUM(C9:C13)","v":0}]
[]
["Niv 1 : 3 - FOURNITURES DE BUREAU"]
["Niv 1 : 110 - PAPIERS"]
["Niv 1 : 120 - COURRIER ET EXPEDITION",126.95,54.180000000100002]
["Niv 1 : 125 - CAHIERS ET DERIVES DE PAPIER",159.15,68.454999999899997]
["Niv 1 : 130 - ECRIRE ET CORRIGER",35.299999999999997,15.971666666300001]
["Niv 1 : 140 - CLASSEMENT",324.66000000000003,164.55083333370001]
["Niv 1 : 150 - PETIT MATERIEL BUREAU ET ECOLE"]
["Niv 1 : 210 - TRAVAUX MANUELS",null,null,0]
["Niv 1 : 220 - DESSIN SCOLAIRE ET PROFESSIONNEL"]
["FOURNITURE",{"$f":"SUM(B16:B24)","v":646.06000000000006},{"$f":"SUM(C16:C24)","v":303.15750000000003}]
[]
["Niv 1 : 4 - MiCrO INFORMATIQUE"]
["Niv 1 : 190 - INFORMATIQUE"]
["MICRO",{"$f":"SUM(B27:B28)","v":0},{"$f":"SUM(C27:C28)","v":0}]
[]
["Niv 1 : 9 - SERVICES/PERSONNALISATION"]
["Niv 1 : 900 - Marketing",null,null,0]
["IMAGE",{"$f":"SUM(B31:B32)","v":0},{"$f":"SUM(C31:C32)","v":0}]
[]
["1 - MOBILIER     ",{"$f":"Journalier!B8","v":0},{"$f":"Journalier!C8","v":0}]
["2 - BUREAUTIQUE",{"$f":"Journalier!B14","v":0},{"$f":"Journalier!C14","v":0}]
["3 - FOURNITURES DE BUREAU",{"$f":"Journalier!B25","v":646.06000000000006},{"$f":"Journalier!C25","v":303.15750000000003}]
["4 - MiCrO INFORMATIQUE",{"$f":"Journalier!B29","v":0},{"$f":"Journalier!C29","v":0}]
["9 - COPIE IMPRIMERIE",{"$f":"B33","v":0},{"$f":"C33","v":0}]
["Total Magasin",{"$f":"SUM(B35:B39)","v":646.06000000000006},{"$f":"SUM(C35:C39)","v":303.15750000000003}]
[]
[]
["DATE","MOBILIER",null,"BUREAUTIQUE",null,"FOURNITURES",null,"MICRO",null,"COPIE IMPRIMERIE",null,"TRANSAC           JOUR"]
[null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[{"$f":"IF(WEEKDAY(TODAY()-1,2)=7,TODAY()-2,TODAY()-1)","v":"2022-03-19"},{"$f":"B35","v":0},{"$f":"C35","v":0},{"$f":"B36","v":0},{"$f":"C36","v":0},{"$f":"B37","v":646.06000000000006},{"$f":"C37","v":303.15750000000003},{"$f":"B38","v":0},{"$f":"C38","v":0},{"$f":"B39","v":0},{"$f":"C39","v":0},{"$f":"D9","v":87}]
[]
[null,"En rouge les cellules à copier/coller dans les onglets de suivi mensuel "]

{"sheet":"JANVIER","index":4,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Janvier",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":0},{"$f":"IF(C6,1,0)","v":1},"2022-01-03",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":1},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-01-04"},110,190,60,null,null,null,null,null,null,null,null,170,190,1.1176470588235294,""]
[0,1,"2022-01-05",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-06",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-07",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-08",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,{"$f":"C12+1","v":"2022-01-09"},{"$f":"IF(SUM(D11:D12)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E11:E12)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ",{"$f":"IF(SUM(R11:R12)>(R44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"}]
[0,1,"2022-01-10",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D14+F14+H14+J14+L14","v":0},{"$f":"SUM(E14+G14+I14+K14+M14)","v":0},"%",""]
[0,1,"2022-01-11",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D15+F15+H15+J15+L15","v":0},0,"%",""]
[0,1,"2022-01-12",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D16+F16+H16+J16+L16","v":0},0,"%",""]
[0,1,"2022-01-13",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-14",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-15",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-01-16",{"$f":"IF(SUM(D14:D19)+SUM(D11:D12)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E14:E19)+SUM(E11:E12)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ"]
[0,1,"2022-01-17",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-18",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-19",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-20",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-21",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-22",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-01-23",{"$f":"IF(SUM(D14:D19)+SUM(D11:D12)+SUM(D21:D26)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E14:E19)+SUM(E11:E12)+SUM(E21:E26)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ"]
[0,1,"2022-01-24",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-25",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-26",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-27",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-28",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-01-29",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-01-30",{"$f":"IF(SUM(D21:D26)+SUM(D14:D19)+SUM(D28:D33)+SUM(D8:D12)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":"ä"},{"$f":"IF(SUM(E21:E26)+SUM(E14:E19)+SUM(E28:E33)+SUM(E8:E12)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":"ä"},"ä","æ","æ","æ","æ","æ","æ","æ","æ","ä","ä","ä","æ"]
[0,1,"2022-01-31",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-02-01"]
[null,null,"2022-02-02"]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":"ä"},"ä","ä","æ","æ","æ","æ","æ","æ","æ","æ","ä","ä","ä","æ"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,""]
[]
[{"$f":"SUM(A7:A37)","v":1},{"$f":"SUM(B7:B37)","v":25},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":110},190,60,0,0,0,0,0,0,0,0,{"$f":"SUM(O8:O37)","v":170},{"$f":"SUM(P7:P37)","v":190},1.1176470588235294,""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD",{"$f":"'AOP22 - 035'!B4","v":0},{"$f":"'AOP22 - 035'!B19","v":0},{"$f":"'AOP22 - 035'!B6","v":0},{"$f":"'AOP22 - 035'!B21","v":0},{"$f":"'AOP22 - 035'!B8","v":0},{"$f":"'AOP22 - 035'!B23","v":0},{"$f":"'AOP22 - 035'!B10","v":0},{"$f":"'AOP22 - 035'!B25","v":0},{"$f":"'AOP22 - 035'!B12","v":0},{"$f":"'AOP22 - 035'!B27","v":0},4500,{"$f":"D44+F44+H44+J44+L44","v":0},{"$f":"E44+G44+I44+K44+M44","v":0},0.41,55]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":"ä"},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":"ä"},"ä","æ","æ","æ","æ","æ","æ","æ","æ","ä","ä",{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"ä"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$f":"SUM(F41/F44)","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$f":"SUM(H41/H44)","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$f":"SUM(N41/N44)","v":0},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#DIV/0!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#DIV/0!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":0.70764705882352952},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#DIV/0!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},"æ",{"$error":"#DIV/0!"},{"$error":"#DIV/0!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":24}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":-4.583333333333333},-7.916666666666667,-2.5,0,0,0,0,0,0,0,187.5,{"$f":"D51+F51+H51+J51+L51","v":-7.083333333333333},{"$f":"E51+G51+I51+K51+M51","v":-7.916666666666667},"Nb de jours dans le mois",{"$f":"B41","v":25}]
[null,null,null,{"$f":"D41/$A$41","v":110},{"$f":"E41/$A$41","v":190},60,0,0,0,0,0,0,0,0,170,190,"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":0.04}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":60},null,{"$f":"+G41+K41","v":0},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":-2.5},{"$f":"+G51+K51","v":0}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":"æ"}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#DIV/0!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#DIV/0!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":0},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":0}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":110},{"$f":"SUM(E6:E11)","v":190},{"$f":"SUM(D13:D18)","v":0},{"$f":"SUM(E13:E18)","v":0},{"$f":"SUM(D20:D25)","v":0},{"$f":"SUM(E20:E25)","v":0},{"$f":"SUM(D27:D32)","v":0},{"$f":"SUM(E27:E32)","v":0},{"$f":"SUM(D34:D39)","v":0},{"$f":"SUM(E34:E39)","v":0},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":"OK"},{"$f":"SUM(E65,G65,I65,K65,M65)","v":110},190,null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":60},{"$f":"SUM(G6:G11)","v":0},{"$f":"SUM(F13:F18)","v":0},{"$f":"SUM(G13:G18)","v":0},{"$f":"SUM(F20:F25)","v":0},{"$f":"SUM(G20:G25)","v":0},{"$f":"SUM(F27:F32)","v":0},{"$f":"SUM(G27:G32)","v":0},{"$f":"SUM(F34:F39)","v":0},{"$f":"SUM(G34:G39)","v":0},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":"OK"},60,0,null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":0},{"$f":"SUM(I6:I11)","v":0},{"$f":"SUM(H13:H18)","v":0},{"$f":"SUM(I13:I18)","v":0},{"$f":"SUM(H20:H25)","v":0},{"$f":"SUM(I20:I25)","v":0},{"$f":"SUM(H27:H32)","v":0},{"$f":"SUM(I27:I32)","v":0},{"$f":"SUM(H34:H39)","v":0},{"$f":"SUM(I34:I39)","v":0},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":"OK"},0,0,null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":0},{"$f":"SUM(K6:K11)","v":0},{"$f":"SUM(J13:J18)","v":0},{"$f":"SUM(K13:K18)","v":0},{"$f":"SUM(J20:J25)","v":0},{"$f":"SUM(K20:K25)","v":0},{"$f":"SUM(J27:J32)","v":0},{"$f":"SUM(K27:K32)","v":0},{"$f":"SUM(J34:J39)","v":0},{"$f":"SUM(K34:K39)","v":0},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":"OK"},0,0,null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":0},{"$f":"SUM(M6:M11)","v":0},{"$f":"SUM(L13:L18)","v":0},{"$f":"SUM(M13:M18)","v":0},{"$f":"SUM(L20:L25)","v":0},{"$f":"SUM(M20:M25)","v":0},{"$f":"SUM(L27:L32)","v":0},{"$f":"SUM(M27:M32)","v":0},{"$f":"SUM(L34:L39)","v":0},{"$f":"SUM(M34:M39)","v":0},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":"OK"},0,0,null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":60},{"$f":"SUM(F66,F68)","v":0},0,0,0,0,0,0,0,0,null,null,60,0,null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":0}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":170},{"$f":"SUM(F65:F69)","v":190},0,0,0,0,0,0,0,0,null,null,{"$f":"SUM(Q65:Q69)","v":170},{"$f":"SUM(R65:R69)","v":190},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":0},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":"OK"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":0},0.1]

{"sheet":"FEVRIER","index":5,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Février",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":0},{"$f":"IF(C6,1,0)","v":1},"2022-02-01",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":0},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-02-02"},null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-03",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-04",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-05",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,{"$f":"C11+1","v":"2022-02-06"},{"$f":"IF(SUM(D10:D11)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E10:E11)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ"]
[0,1,{"$f":"C12+1","v":"2022-02-07"},null,null,null,null,null,null,null,null,null,null,null,{"$f":"D13+F13+H13+J13+L13","v":0},{"$f":"SUM(E13+G13+I13+K13+M13)","v":0},"%",""]
[0,1,"2022-02-08",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D14+F14+H14+J14+L14","v":0},{"$f":"SUM(E14+G14+I14+K14+M14)","v":0},"%",""]
[0,1,"2022-02-09",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D15+F15+H15+J15+L15","v":0},0,"%",""]
[0,1,"2022-02-10",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D16+F16+H16+J16+L16","v":0},0,"%",""]
[0,1,"2022-02-11",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-12",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D18+F18+H18+J18+L18","v":0},0,"%",""]
[null,null,"2022-02-13",{"$f":"IF(SUM(D13:D18)+SUM(D10:D11)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E13:E18)+SUM(E10:E11)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ"]
[0,1,"2022-02-14",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-15",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-16",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-17",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-18",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-19",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-02-20",{"$f":"IF(SUM(D13:D18)+SUM(D10:D11)+SUM(D20:D25)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E13:E18)+SUM(E10:E11)+SUM(E20:E25)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ"]
[0,1,"2022-02-21",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-22",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-23",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-24",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-25",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-02-26",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-02-27",{"$f":"IF(SUM(D20:D25)+SUM(D13:D18)+SUM(D27:D32)+SUM(D7:D11)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E20:E25)+SUM(E13:E18)+SUM(E27:E32)+SUM(E7:E11)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ"]
[0,1,"2022-02-28",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-03-01",{"$f":"IF(SUM(D27:D32)+SUM(D20:D25)+SUM(D34)+SUM(D13:D18)+SUM(D7:D11)>(D$44*(4/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E27:E32)+SUM(E20:E25)+SUM(E34)+SUM(E13:E18)+SUM(E7:E11)>(E$44*(4/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ"]
[null,null,"2022-03-02"]
[null,null,"2022-03-03"]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,""]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":0},{"$f":"SUM(B7:B37)","v":24},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":0},0,0,0,0,0,0,0,0,0,0,{"$f":"SUM(O8:O37)","v":0},{"$f":"SUM(P7:P37)","v":0},"%",""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD",{"$f":"'AOP22 - 035'!D4","v":0},{"$f":"'AOP22 - 035'!D19","v":0},{"$f":"'AOP22 - 035'!D6","v":0},{"$f":"'AOP22 - 035'!D21","v":0},{"$f":"'AOP22 - 035'!D8","v":0},{"$f":"'AOP22 - 035'!D23","v":0},{"$f":"'AOP22 - 035'!D10","v":0},{"$f":"'AOP22 - 035'!D25","v":0},{"$f":"'AOP22 - 035'!D12","v":0},{"$f":"'AOP22 - 035'!D27","v":0},4500,{"$f":"D44+F44+H44+J44+L44","v":0},{"$f":"E44+G44+I44+K44+M44","v":0},0.41,55]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#DIV/0!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"ä"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$f":"SUM(F41/F44)","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$f":"SUM(H41/H44)","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$f":"SUM(N41/N44)","v":0},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#DIV/0!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#DIV/0!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":""},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#DIV/0!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},"æ",{"$error":"#DIV/0!"},{"$error":"#DIV/0!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":24}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":0},0,0,0,0,0,0,0,0,0,187.5,{"$f":"D51+F51+H51+J51+L51","v":0},{"$f":"E51+G51+I51+K51+M51","v":0},"Nb de jours dans le mois",{"$f":"B41","v":24}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#DIV/0!"}},{"$f":"E41/$A$41","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":0}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":0},null,{"$f":"+G41+K41","v":0},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":0},{"$f":"+G51+K51","v":0}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":"æ"}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#DIV/0!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#DIV/0!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":0},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":0}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":0},{"$f":"SUM(E6:E11)","v":0},{"$f":"SUM(D13:D18)","v":0},{"$f":"SUM(E13:E18)","v":0},{"$f":"SUM(D20:D25)","v":0},{"$f":"SUM(E20:E25)","v":0},{"$f":"SUM(D27:D32)","v":0},{"$f":"SUM(E27:E32)","v":0},{"$f":"SUM(D34:D39)","v":0},{"$f":"SUM(E34:E39)","v":0},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":"OK"},{"$f":"SUM(E65,G65,I65,K65,M65)","v":0},0,null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":0},{"$f":"SUM(G6:G11)","v":0},{"$f":"SUM(F13:F18)","v":0},{"$f":"SUM(G13:G18)","v":0},{"$f":"SUM(F20:F25)","v":0},{"$f":"SUM(G20:G25)","v":0},{"$f":"SUM(F27:F32)","v":0},{"$f":"SUM(G27:G32)","v":0},{"$f":"SUM(F34:F39)","v":0},{"$f":"SUM(G34:G39)","v":0},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":"OK"},0,0,null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":0},{"$f":"SUM(I6:I11)","v":0},{"$f":"SUM(H13:H18)","v":0},{"$f":"SUM(I13:I18)","v":0},{"$f":"SUM(H20:H25)","v":0},{"$f":"SUM(I20:I25)","v":0},{"$f":"SUM(H27:H32)","v":0},{"$f":"SUM(I27:I32)","v":0},{"$f":"SUM(H34:H39)","v":0},{"$f":"SUM(I34:I39)","v":0},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":"OK"},0,0,null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":0},{"$f":"SUM(K6:K11)","v":0},{"$f":"SUM(J13:J18)","v":0},{"$f":"SUM(K13:K18)","v":0},{"$f":"SUM(J20:J25)","v":0},{"$f":"SUM(K20:K25)","v":0},{"$f":"SUM(J27:J32)","v":0},{"$f":"SUM(K27:K32)","v":0},{"$f":"SUM(J34:J39)","v":0},{"$f":"SUM(K34:K39)","v":0},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":"OK"},0,0,null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":0},{"$f":"SUM(M6:M11)","v":0},{"$f":"SUM(L13:L18)","v":0},{"$f":"SUM(M13:M18)","v":0},{"$f":"SUM(L20:L25)","v":0},{"$f":"SUM(M20:M25)","v":0},{"$f":"SUM(L27:L32)","v":0},{"$f":"SUM(M27:M32)","v":0},{"$f":"SUM(L34:L39)","v":0},{"$f":"SUM(M34:M39)","v":0},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":"OK"},0,0,null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":0},{"$f":"SUM(F66,F68)","v":0},0,0,0,0,0,0,0,0,null,null,0,0,null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#DIV/0!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":0},{"$f":"SUM(F65:F69)","v":0},0,0,0,0,0,0,0,0,null,null,{"$f":"SUM(Q65:Q69)","v":0},{"$f":"SUM(R65:R69)","v":0},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#DIV/0!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":"OK"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#DIV/0!"}},0.1]

{"sheet":"MARS","index":6,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Mars",null,null,2022,null,5]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":0},{"$f":"IF(C6,1,0)","v":1},{"$f":"C6+1","v":"2022-03-01"},null,null,null,null,null,null,null,null,null,null,null,0,0,"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":0},{"$f":"IF(C7,1,0)","v":1},"2022-03-02",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-03",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,{"$f":"C9+1","v":"2022-03-04"},null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-05",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-03-06",{"$f":"IF(SUM(D7:D11)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E6:E11)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ",{"$f":"IF(ISERROR(IF(SUM(P6:P11)/SUM(O6:O11)>=$Q$44,\"ä\",\"æ\")),\"\",IF(SUM(P6:P11)/SUM(O6:O11)>=$Q$44,\"ä\",\"æ\"))","v":""},{"$f":"IF(ISERROR(IF(SUM(O6:O11)/SUM(N6:N11)>=$R$44,\"ä\",\"æ\")),\"\",IF(SUM(O6:O11)/SUM(N6:N11)>=$R$44,\"ä\",\"æ\"))","v":""}]
[0,1,"2022-03-07",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D13+F13+H13+J13+L13","v":0},{"$f":"SUM(E13+G13+I13+K13+M13)","v":0},{"$f":"IF(ISERROR(P13/O13),\"%\",P13/O13)","v":"%"},""]
[0,1,"2022-03-08",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D14+F14+H14+J14+L14","v":0},{"$f":"SUM(E14+G14+I14+K14+M14)","v":0},"%",""]
[0,1,"2022-03-09",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D15+F15+H15+J15+L15","v":0},0,"%",""]
[0,1,"2022-03-10",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D16+F16+H16+J16+L16","v":0},{"$f":"SUM(E16+G16+I16+K16+M16)","v":0},"%",""]
[0,1,"2022-03-11",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D17+F17+H17+J17+L17","v":0},0,"%",""]
[0,1,"2022-03-12",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-03-13",{"$f":"IF(SUM(D13:D18)+SUM(D7:D11)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(E13:E18)+SUM(E6:E11)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":"æ"},"æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ","æ"]
[0,1,"2022-03-14",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D20+F20+H20+J20+L20","v":0},0,{"$f":"IF(ISERROR(P20/O20),\"%\",P20/O20)","v":"%"},""]
[0,1,"2022-03-15",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-16",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[1,1,"2022-03-17",48.19,18.691700000000001,1790.32,483.3383,1364.15,446.53149999999999,0,0,0,0,87,3202.66,948.56150000000002,0.29617926973203529,36.812183908045974]
[0,1,"2022-03-18",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-19",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-03-20",{"$f":"IF(SUM(D13:D18)+SUM(D6:D11)+SUM(D20:D25)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":"ä"},"ä","ä","ä","ä","ä","æ","æ","æ","æ","ä","ä","ä","ä","ä"]
[0,1,"2022-03-21",null,null,null,null,null,null,null,null,null,null,null,{"$f":"D27+F27+H27+J27+L27","v":0},0,{"$f":"IF(ISERROR(P27/O27),\"%\",P27/O27)","v":"%"},""]
[0,1,"2022-03-22",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-23",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-24",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-25",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-26",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,"2022-03-27",{"$f":"IF(SUM(D20:D25)+SUM(D13:D18)+SUM(D27:D32)+SUM(D6:D11)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":"ä"},"ä","ä","ä","ä","ä","æ","æ","æ","æ","ä","ä","ä","æ","æ"]
[0,1,{"$f":"IF($Q$2=4,\"\",C33+1)","v":"2022-03-28"},null,null,null,null,null,null,null,null,null,null,null,{"$f":"D34+F34+H34+J34+L34","v":0},0,{"$f":"IF(ISERROR(P34/O34),\"%\",P34/O34)","v":"%"},""]
[0,1,"2022-03-29",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-30",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[0,1,"2022-03-31",null,null,null,null,null,null,null,null,null,null,null,0,0,"%",""]
[null,null,null,{"$f":"IF(SUM(D20:D25)+SUM(D13:D18)+SUM(D27:D32)+SUM(D7:D11)+SUM(D34:D37)>(D44*(5/$Q$2)),\"ä\",\"æ\")","v":"ä"},{"$f":"IF(SUM(E20:E25)+SUM(E13:E18)+SUM(E27:E32)+SUM(E7:E11)+SUM(E34:E37)>(E44*(5/$Q$2)),\"ä\",\"æ\")","v":"ä"},"ä","ä","ä","ä","æ","æ","æ","æ","ä","ä","ä","æ","æ"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,""]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":1},{"$f":"SUM(B7:B37)","v":27},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":48.19},{"$f":"SUM(E7:E37)","v":18.691700000000001},1790.32,483.3383,1364.15,446.53149999999999,0,0,0,0,{"$f":"SUM(N7:N37)","v":87},{"$f":"SUM(O8:O37)","v":3202.66},{"$f":"SUM(P7:P37)","v":948.56150000000002},0.29617926973203529,36.812183908045974]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD",{"$f":"'AOP22 - 035'!F4","v":0},{"$f":"'AOP22 - 035'!F19","v":0},{"$f":"'AOP22 - 035'!F6","v":0},{"$f":"'AOP22 - 035'!F21","v":0},{"$f":"'AOP22 - 035'!F8","v":0},{"$f":"'AOP22 - 035'!F23","v":0},{"$f":"'AOP22 - 035'!F10","v":0},{"$f":"'AOP22 - 035'!F25","v":0},{"$f":"'AOP22 - 035'!F12","v":0},{"$f":"'AOP22 - 035'!F27","v":0},null,{"$f":"D44+F44+H44+J44+L44","v":0},{"$f":"E44+G44+I44+K44+M44","v":0},0.41,55]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":"ä"},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":"ä"},"ä","ä","ä","ä","æ","æ","æ","æ","ä","ä","ä",{"$f":"IF(Q41>(Q44),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(R41>(R44),\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$f":"SUM(F41/F44)","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$f":"SUM(H41/H44)","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#DIV/0!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#DIV/0!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":-0.11382073026796469},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":-18.187816091954026}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#DIV/0!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#DIV/0!"}},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"},{"$error":"#DIV/0!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":26}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":-1.8534615384615383},-0.71891153846153855,-68.85846153846154,-18.589934615384614,-52.467307692307699,-17.17428846153846,0,0,0,0,-3.3461538461538463,{"$f":"D51+F51+H51+J51+L51","v":-123.17923076923078},{"$f":"E51+G51+I51+K51+M51","v":-36.483134615384614},"Nb de jours dans le mois",27]
[null,null,null,{"$f":"D41/$A$41","v":48.19},{"$f":"E41/$A$41","v":18.691700000000001},1790.32,483.3383,1364.15,446.53149999999999,0,0,0,0,87,3202.66,948.56150000000002,"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":3.7037037037037035E-2}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":1790.32},null,{"$f":"+G41+K41","v":483.3383},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":-68.85846153846154},{"$f":"+G51+K51","v":-18.589934615384614}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":"ä"}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#DIV/0!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#DIV/0!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":0},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":0}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":0},{"$f":"SUM(E6:E11)","v":0},{"$f":"SUM(D13:D18)","v":0},{"$f":"SUM(E13:E18)","v":0},{"$f":"SUM(D20:D25)","v":48.19},{"$f":"SUM(E20:E25)","v":18.691700000000001},{"$f":"SUM(D27:D32)","v":0},{"$f":"SUM(E27:E32)","v":0},{"$f":"SUM(D34:D39)","v":0},{"$f":"SUM(E34:E39)","v":0},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":"OK"},{"$f":"SUM(E65,G65,I65,K65,M65)","v":48.19},18.691700000000001,null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":0},{"$f":"SUM(G6:G11)","v":0},{"$f":"SUM(F13:F18)","v":0},{"$f":"SUM(G13:G18)","v":0},{"$f":"SUM(F20:F25)","v":1790.32},{"$f":"SUM(G20:G25)","v":483.3383},{"$f":"SUM(F27:F32)","v":0},{"$f":"SUM(G27:G32)","v":0},{"$f":"SUM(F34:F39)","v":0},{"$f":"SUM(G34:G39)","v":0},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":"OK"},1790.32,483.3383,null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":0},{"$f":"SUM(I6:I11)","v":0},{"$f":"SUM(H13:H18)","v":0},{"$f":"SUM(I13:I18)","v":0},{"$f":"SUM(H20:H25)","v":1364.15},{"$f":"SUM(I20:I25)","v":446.53149999999999},{"$f":"SUM(H27:H32)","v":0},{"$f":"SUM(I27:I32)","v":0},{"$f":"SUM(H34:H39)","v":0},{"$f":"SUM(I34:I39)","v":0},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":"OK"},1364.15,446.53149999999999,null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":0},{"$f":"SUM(K6:K11)","v":0},{"$f":"SUM(J13:J18)","v":0},{"$f":"SUM(K13:K18)","v":0},{"$f":"SUM(J20:J25)","v":0},{"$f":"SUM(K20:K25)","v":0},{"$f":"SUM(J27:J32)","v":0},{"$f":"SUM(K27:K32)","v":0},{"$f":"SUM(J34:J39)","v":0},{"$f":"SUM(K34:K39)","v":0},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":"OK"},0,0,null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":0},{"$f":"SUM(M6:M11)","v":0},{"$f":"SUM(L13:L18)","v":0},{"$f":"SUM(M13:M18)","v":0},{"$f":"SUM(L20:L25)","v":0},{"$f":"SUM(M20:M25)","v":0},{"$f":"SUM(L27:L32)","v":0},{"$f":"SUM(M27:M32)","v":0},{"$f":"SUM(L34:L39)","v":0},{"$f":"SUM(M34:M39)","v":0},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":"OK"},0,0,null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":0},{"$f":"SUM(F66,F68)","v":0},0,0,1790.32,483.3383,0,0,0,0,null,null,1790.32,483.3383,null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":0}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":0},{"$f":"SUM(F65:F69)","v":0},0,0,3202.66,948.56150000000002,0,0,0,0,null,null,{"$f":"SUM(Q65:Q69)","v":3202.66},{"$f":"SUM(R65:R69)","v":948.56150000000002},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":0},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":"OK"},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":"OK"},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":0},0.1]

{"sheet":"AVRIL","index":7,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Avril",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C6,1,0)","v":1},"2022-04-01",{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-04-02"},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C8+1","v":"2022-04-03"},{"$f":"IF(SUM(D7:D8)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E7:E8)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-04-04",{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-05",{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-06",{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,{"$f":"C12+1","v":"2022-04-07"},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D13+F13+H13+J13+L13","v":{"$error":"#REF!"}},{"$f":"SUM(E13+G13+I13+K13+M13)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-04-08",{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D14+F14+H14+J14+L14","v":{"$error":"#REF!"}},{"$f":"SUM(E14+G14+I14+K14+M14)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-04-09",{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D15+F15+H15+J15+L15","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[null,null,"2022-04-10",{"$f":"IF(SUM(D10:D15)+SUM(D7:D8)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E10:E15)+SUM(E7:E8)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-04-11",{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D17+F17+H17+J17+L17","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-12",{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-13",{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-14",{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-15",{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-16",{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-04-17",{"$f":"IF(SUM(D10:D15)+SUM(D7:D8)+SUM(D17:D22)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E10:E15)+SUM(E7:E8)+SUM(E17:E22)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-04-18",{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-19",{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-20",{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-21",{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-22",{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-23",{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-04-24",{"$f":"IF(SUM(D17:D22)+SUM(D10:D15)+SUM(D24:D29)+SUM(D7:D8)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E17:E22)+SUM(E10:E15)+SUM(E24:E29)+SUM(E7:E8)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-04-25",{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-26",{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-27",{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-28",{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-29",{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-04-30",{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-05-01",{"$f":"IF(SUM(D24:D29)+SUM(D17:D22)+SUM(D31:D36)+SUM(D10:D15)+SUM(D7:D8)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E24:E29)+SUM(E17:E22)+SUM(E31:E36)+SUM(E10:E15)+SUM(E7:E8)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,""]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":{"$error":"#REF!"}},{"$f":"SUM(B7:B37)","v":26},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},0,{"$f":"SUM(O8:O37)","v":{"$error":"#REF!"}},{"$f":"SUM(P7:P37)","v":{"$error":"#REF!"}},"%",""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD"]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(F41/F44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(H41/H44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#REF!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#REF!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":""},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#DIV/0!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":{"$error":"#REF!"}}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"D51+F51+H51+J51+L51","v":{"$error":"#REF!"}},{"$f":"E51+G51+I51+K51+M51","v":{"$error":"#REF!"}},"Nb de jours dans le mois",{"$f":"B41","v":26}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#REF!"}},{"$f":"E41/$A$41","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":{"$error":"#REF!"}},null,{"$f":"+G41+K41","v":{"$error":"#REF!"}},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":{"$error":"#REF!"}},{"$f":"+G51+K51","v":{"$error":"#REF!"}}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":{"$error":"#REF!"}}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#REF!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#REF!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":{"$error":"#REF!"}},{"$f":"SUM(E6:E11)","v":{"$error":"#REF!"}},{"$f":"SUM(D13:D18)","v":{"$error":"#REF!"}},{"$f":"SUM(E13:E18)","v":{"$error":"#REF!"}},{"$f":"SUM(D20:D25)","v":{"$error":"#REF!"}},{"$f":"SUM(E20:E25)","v":{"$error":"#REF!"}},{"$f":"SUM(D27:D32)","v":{"$error":"#REF!"}},{"$f":"SUM(E27:E32)","v":{"$error":"#REF!"}},{"$f":"SUM(D34:D39)","v":{"$error":"#REF!"}},{"$f":"SUM(E34:E39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"SUM(E65,G65,I65,K65,M65)","v":{"$error":"#REF!"}},{"$error":"#REF!"},null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":{"$error":"#REF!"}},{"$f":"SUM(G6:G11)","v":{"$error":"#REF!"}},{"$f":"SUM(F13:F18)","v":{"$error":"#REF!"}},{"$f":"SUM(G13:G18)","v":{"$error":"#REF!"}},{"$f":"SUM(F20:F25)","v":{"$error":"#REF!"}},{"$f":"SUM(G20:G25)","v":{"$error":"#REF!"}},{"$f":"SUM(F27:F32)","v":{"$error":"#REF!"}},{"$f":"SUM(G27:G32)","v":{"$error":"#REF!"}},{"$f":"SUM(F34:F39)","v":{"$error":"#REF!"}},{"$f":"SUM(G34:G39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":{"$error":"#REF!"}},{"$f":"SUM(I6:I11)","v":{"$error":"#REF!"}},{"$f":"SUM(H13:H18)","v":{"$error":"#REF!"}},{"$f":"SUM(I13:I18)","v":{"$error":"#REF!"}},{"$f":"SUM(H20:H25)","v":{"$error":"#REF!"}},{"$f":"SUM(I20:I25)","v":{"$error":"#REF!"}},{"$f":"SUM(H27:H32)","v":{"$error":"#REF!"}},{"$f":"SUM(I27:I32)","v":{"$error":"#REF!"}},{"$f":"SUM(H34:H39)","v":{"$error":"#REF!"}},{"$f":"SUM(I34:I39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":{"$error":"#REF!"}},{"$f":"SUM(K6:K11)","v":{"$error":"#REF!"}},{"$f":"SUM(J13:J18)","v":{"$error":"#REF!"}},{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},{"$f":"SUM(J20:J25)","v":{"$error":"#REF!"}},{"$f":"SUM(K20:K25)","v":{"$error":"#REF!"}},{"$f":"SUM(J27:J32)","v":{"$error":"#REF!"}},{"$f":"SUM(K27:K32)","v":{"$error":"#REF!"}},{"$f":"SUM(J34:J39)","v":{"$error":"#REF!"}},{"$f":"SUM(K34:K39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":{"$error":"#REF!"}},{"$f":"SUM(M6:M11)","v":{"$error":"#REF!"}},{"$f":"SUM(L13:L18)","v":{"$error":"#REF!"}},{"$f":"SUM(M13:M18)","v":{"$error":"#REF!"}},{"$f":"SUM(L20:L25)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M25)","v":{"$error":"#REF!"}},{"$f":"SUM(L27:L32)","v":{"$error":"#REF!"}},{"$f":"SUM(M27:M32)","v":{"$error":"#REF!"}},{"$f":"SUM(L34:L39)","v":{"$error":"#REF!"}},{"$f":"SUM(M34:M39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":{"$error":"#REF!"}},{"$f":"SUM(F66,F68)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#REF!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":{"$error":"#REF!"}},{"$f":"SUM(F65:F69)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$f":"SUM(Q65:Q69)","v":{"$error":"#REF!"}},{"$f":"SUM(R65:R69)","v":{"$error":"#REF!"}},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#REF!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#REF!"}},0.1]

{"sheet":"MAI","index":8,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Mai",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C6,1,0)","v":1},"2022-05-02",{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-05-03"},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-04",{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-05",{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-06",{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-07",{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C12+1","v":"2022-05-08"},{"$f":"IF(SUM(D7:D12)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E7:E12)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-05-09",{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D14+F14+H14+J14+L14","v":{"$error":"#REF!"}},{"$f":"SUM(E14+G14+I14+K14+M14)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-05-10",{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D15+F15+H15+J15+L15","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-11",{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D16+F16+H16+J16+L16","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-12",{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D17+F17+H17+J17+L17","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-13",{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-14",{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-05-15",{"$f":"IF(SUM(D14:D19)+SUM(D7:D12)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E14:E19)+SUM(E7:E12)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F14:F19)+SUM(F7:F12)>(F44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-05-16",{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-17",{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-18",{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-19",{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-20",{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-21",{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-05-22",{"$f":"IF(SUM(D14:D19)+SUM(D7:D12)+SUM(D21:D26)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E14:E19)+SUM(E7:E12)+SUM(E21:E26)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-05-23",{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-24",{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-25",{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-26",{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-27",{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-28",{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-05-29",{"$f":"IF(SUM(D21:D26)+SUM(D14:D19)+SUM(D28:D33)+SUM(D7:D12)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E21:E26)+SUM(E14:E19)+SUM(E28:E33)+SUM(E7:E12)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-05-30",{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-05-31",{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-06-01",{"$f":"IF(SUM(D28:D33)+SUM(D21:D26)+SUM(D35:D36)+SUM(D14:D19)+SUM(D7:D12)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E28:E33)+SUM(E21:E26)+SUM(E35:E36)+SUM(E14:E19)+SUM(E7:E12)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,""]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":{"$error":"#REF!"}},{"$f":"SUM(B7:B37)","v":26},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},0,{"$f":"SUM(O8:O37)","v":{"$error":"#REF!"}},{"$f":"SUM(P7:P37)","v":{"$error":"#REF!"}},"%",""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD"]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(F41/F44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(H41/H44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#REF!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#REF!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":""},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#DIV/0!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":{"$error":"#REF!"}}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"D51+F51+H51+J51+L51","v":{"$error":"#REF!"}},{"$f":"E51+G51+I51+K51+M51","v":{"$error":"#REF!"}},"Nb de jours dans le mois",{"$f":"B41","v":26}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#REF!"}},{"$f":"E41/$A$41","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":{"$error":"#REF!"}},null,{"$f":"+G41+K41","v":{"$error":"#REF!"}},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":{"$error":"#REF!"}},{"$f":"+G51+K51","v":{"$error":"#REF!"}}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":{"$error":"#REF!"}}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#REF!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#REF!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":{"$error":"#REF!"}},{"$f":"SUM(E6:E11)","v":{"$error":"#REF!"}},{"$f":"SUM(D13:D18)","v":{"$error":"#REF!"}},{"$f":"SUM(E13:E18)","v":{"$error":"#REF!"}},{"$f":"SUM(D20:D25)","v":{"$error":"#REF!"}},{"$f":"SUM(E20:E25)","v":{"$error":"#REF!"}},{"$f":"SUM(D27:D32)","v":{"$error":"#REF!"}},{"$f":"SUM(E27:E32)","v":{"$error":"#REF!"}},{"$f":"SUM(D34:D39)","v":{"$error":"#REF!"}},{"$f":"SUM(E34:E39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"SUM(E65,G65,I65,K65,M65)","v":{"$error":"#REF!"}},{"$error":"#REF!"},null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":{"$error":"#REF!"}},{"$f":"SUM(G6:G11)","v":{"$error":"#REF!"}},{"$f":"SUM(F13:F18)","v":{"$error":"#REF!"}},{"$f":"SUM(G13:G18)","v":{"$error":"#REF!"}},{"$f":"SUM(F20:F25)","v":{"$error":"#REF!"}},{"$f":"SUM(G20:G25)","v":{"$error":"#REF!"}},{"$f":"SUM(F27:F32)","v":{"$error":"#REF!"}},{"$f":"SUM(G27:G32)","v":{"$error":"#REF!"}},{"$f":"SUM(F34:F39)","v":{"$error":"#REF!"}},{"$f":"SUM(G34:G39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":{"$error":"#REF!"}},{"$f":"SUM(I6:I11)","v":{"$error":"#REF!"}},{"$f":"SUM(H13:H18)","v":{"$error":"#REF!"}},{"$f":"SUM(I13:I18)","v":{"$error":"#REF!"}},{"$f":"SUM(H20:H25)","v":{"$error":"#REF!"}},{"$f":"SUM(I20:I25)","v":{"$error":"#REF!"}},{"$f":"SUM(H27:H32)","v":{"$error":"#REF!"}},{"$f":"SUM(I27:I32)","v":{"$error":"#REF!"}},{"$f":"SUM(H34:H39)","v":{"$error":"#REF!"}},{"$f":"SUM(I34:I39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":{"$error":"#REF!"}},{"$f":"SUM(K6:K11)","v":{"$error":"#REF!"}},{"$f":"SUM(J13:J18)","v":{"$error":"#REF!"}},{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},{"$f":"SUM(J20:J25)","v":{"$error":"#REF!"}},{"$f":"SUM(K20:K25)","v":{"$error":"#REF!"}},{"$f":"SUM(J27:J32)","v":{"$error":"#REF!"}},{"$f":"SUM(K27:K32)","v":{"$error":"#REF!"}},{"$f":"SUM(J34:J39)","v":{"$error":"#REF!"}},{"$f":"SUM(K34:K39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":{"$error":"#REF!"}},{"$f":"SUM(M6:M11)","v":{"$error":"#REF!"}},{"$f":"SUM(L13:L18)","v":{"$error":"#REF!"}},{"$f":"SUM(M13:M18)","v":{"$error":"#REF!"}},{"$f":"SUM(L20:L25)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M25)","v":{"$error":"#REF!"}},{"$f":"SUM(L27:L32)","v":{"$error":"#REF!"}},{"$f":"SUM(M27:M32)","v":{"$error":"#REF!"}},{"$f":"SUM(L34:L39)","v":{"$error":"#REF!"}},{"$f":"SUM(M34:M39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":{"$error":"#REF!"}},{"$f":"SUM(F66,F68)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#REF!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":{"$error":"#REF!"}},{"$f":"SUM(F65:F69)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$f":"SUM(Q65:Q69)","v":{"$error":"#REF!"}},{"$f":"SUM(R65:R69)","v":{"$error":"#REF!"}},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#REF!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#REF!"}},0.1]

{"sheet":"JUIN","index":9,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Juin",null,null,2022,null,5]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C6,1,0)","v":1},"2022-06-01",{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-06-02"},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-03",{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-04",{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C10+1","v":"2022-06-05"},{"$f":"IF(SUM(D7:D10)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E7:E10)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-06-06",{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-07",{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-08",{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$f":"SUM(E14+G14+I14+K14+M14)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-06-09",{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D15+F15+H15+J15+L15","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-10",{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D16+F16+H16+J16+L16","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-11",{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D17+F17+H17+J17+L17","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[null,null,"2022-06-12",{"$f":"IF(SUM(D12:D17)+SUM(D7:D10)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E12:E17)+SUM(E7:E10)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-06-13",{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-14",{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-15",{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-16",{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-17",{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-18",{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-06-19",{"$f":"IF(SUM(D12:D17)+SUM(D7:D10)+SUM(D19:D24)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E12:E17)+SUM(E7:E10)+SUM(E19:E24)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-06-20",{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-21",{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-22",{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-23",{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-24",{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-25",{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-06-26",{"$f":"IF(SUM(D19:D24)+SUM(D12:D17)+SUM(D26:D31)+SUM(D7:D10)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E19:E24)+SUM(E12:E17)+SUM(E26:E31)+SUM(E7:E10)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-06-27",{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-28",{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-29",{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-06-30",{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-07-01",{"$f":"IF(SUM(D26:D31)+SUM(D19:D24)+SUM(D33:D36)+SUM(D12:D17)+SUM(D7:D10)>(D44*(5/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E26:E31)+SUM(E19:E24)+SUM(E33:E36)+SUM(E12:E17)+SUM(E7:E10)>(E44*(5/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,""]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":{"$error":"#REF!"}},{"$f":"SUM(B7:B37)","v":26},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},0,{"$f":"SUM(O8:O37)","v":{"$error":"#REF!"}},{"$f":"SUM(P7:P37)","v":{"$error":"#REF!"}},"%",""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD"]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(F41/F44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(H41/H44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#REF!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#REF!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":""},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#DIV/0!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":{"$error":"#REF!"}}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"D51+F51+H51+J51+L51","v":{"$error":"#REF!"}},{"$f":"E51+G51+I51+K51+M51","v":{"$error":"#REF!"}},"Nb de jours dans le mois",{"$f":"B41","v":26}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#REF!"}},{"$f":"E41/$A$41","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":{"$error":"#REF!"}},null,{"$f":"+G41+K41","v":{"$error":"#REF!"}},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":{"$error":"#REF!"}},{"$f":"+G51+K51","v":{"$error":"#REF!"}}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":{"$error":"#REF!"}}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#REF!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#REF!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":{"$error":"#REF!"}},{"$f":"SUM(E6:E11)","v":{"$error":"#REF!"}},{"$f":"SUM(D13:D18)","v":{"$error":"#REF!"}},{"$f":"SUM(E13:E18)","v":{"$error":"#REF!"}},{"$f":"SUM(D20:D25)","v":{"$error":"#REF!"}},{"$f":"SUM(E20:E25)","v":{"$error":"#REF!"}},{"$f":"SUM(D27:D32)","v":{"$error":"#REF!"}},{"$f":"SUM(E27:E32)","v":{"$error":"#REF!"}},{"$f":"SUM(D34:D39)","v":{"$error":"#REF!"}},{"$f":"SUM(E34:E39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"SUM(E65,G65,I65,K65,M65)","v":{"$error":"#REF!"}},{"$error":"#REF!"},null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":{"$error":"#REF!"}},{"$f":"SUM(G6:G11)","v":{"$error":"#REF!"}},{"$f":"SUM(F13:F18)","v":{"$error":"#REF!"}},{"$f":"SUM(G13:G18)","v":{"$error":"#REF!"}},{"$f":"SUM(F20:F25)","v":{"$error":"#REF!"}},{"$f":"SUM(G20:G25)","v":{"$error":"#REF!"}},{"$f":"SUM(F27:F32)","v":{"$error":"#REF!"}},{"$f":"SUM(G27:G32)","v":{"$error":"#REF!"}},{"$f":"SUM(F34:F39)","v":{"$error":"#REF!"}},{"$f":"SUM(G34:G39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":{"$error":"#REF!"}},{"$f":"SUM(I6:I11)","v":{"$error":"#REF!"}},{"$f":"SUM(H13:H18)","v":{"$error":"#REF!"}},{"$f":"SUM(I13:I18)","v":{"$error":"#REF!"}},{"$f":"SUM(H20:H25)","v":{"$error":"#REF!"}},{"$f":"SUM(I20:I25)","v":{"$error":"#REF!"}},{"$f":"SUM(H27:H32)","v":{"$error":"#REF!"}},{"$f":"SUM(I27:I32)","v":{"$error":"#REF!"}},{"$f":"SUM(H34:H39)","v":{"$error":"#REF!"}},{"$f":"SUM(I34:I39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":{"$error":"#REF!"}},{"$f":"SUM(K6:K11)","v":{"$error":"#REF!"}},{"$f":"SUM(J13:J18)","v":{"$error":"#REF!"}},{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},{"$f":"SUM(J20:J25)","v":{"$error":"#REF!"}},{"$f":"SUM(K20:K25)","v":{"$error":"#REF!"}},{"$f":"SUM(J27:J32)","v":{"$error":"#REF!"}},{"$f":"SUM(K27:K32)","v":{"$error":"#REF!"}},{"$f":"SUM(J34:J39)","v":{"$error":"#REF!"}},{"$f":"SUM(K34:K39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":{"$error":"#REF!"}},{"$f":"SUM(M6:M11)","v":{"$error":"#REF!"}},{"$f":"SUM(L13:L18)","v":{"$error":"#REF!"}},{"$f":"SUM(M13:M18)","v":{"$error":"#REF!"}},{"$f":"SUM(L20:L25)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M25)","v":{"$error":"#REF!"}},{"$f":"SUM(L27:L32)","v":{"$error":"#REF!"}},{"$f":"SUM(M27:M32)","v":{"$error":"#REF!"}},{"$f":"SUM(L34:L39)","v":{"$error":"#REF!"}},{"$f":"SUM(M34:M39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":{"$error":"#REF!"}},{"$f":"SUM(F66,F68)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#REF!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":{"$error":"#REF!"}},{"$f":"SUM(F65:F69)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$f":"SUM(Q65:Q69)","v":{"$error":"#REF!"}},{"$f":"SUM(R65:R69)","v":{"$error":"#REF!"}},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#REF!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#REF!"}},0.1]

{"sheet":"JUILLET","index":10,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Juillet",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C6,1,0)","v":1},"2022-07-01",{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-07-02"},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C8+1","v":"2022-07-03"},{"$f":"IF(SUM(D7:D8)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E7:E8)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-07-04",{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-05",{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-06",{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-07",{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-08",{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$f":"SUM(E14+G14+I14+K14+M14)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-07-09",{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D15+F15+H15+J15+L15","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C15+1","v":"2022-07-10"},{"$f":"IF(SUM(D10:D15)+SUM(D7:D8)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E10:E15)+SUM(E7:E8)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-07-11",{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D17+F17+H17+J17+L17","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-12",{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-13",{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-07-14"]
[{"$error":"#REF!"},1,"2022-07-15",{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-16",{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C22+1","v":"2022-07-17"},{"$f":"IF(SUM(D10:D15)+SUM(D7:D8)+SUM(D17:D22)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E10:E15)+SUM(E7:E8)+SUM(E17:E22)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-07-18",{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-19",{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-20",{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-21",{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-22",{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-23",{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C29+1","v":"2022-07-24"},{"$f":"IF(SUM(D17:D22)+SUM(D10:D15)+SUM(D24:D29)+SUM(D7:D8)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E17:E22)+SUM(E10:E15)+SUM(E24:E29)+SUM(E7:E8)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-07-25",{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-26",{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-27",{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-28",{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-29",{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-07-30",{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-07-31",{"$f":"IF(SUM(D24:D29)+SUM(D17:D22)+SUM(D31:D36)+SUM(D10:D15)+SUM(D7:D8)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E24:E29)+SUM(E17:E22)+SUM(E31:E36)+SUM(E10:E15)+SUM(E7:E8)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,""]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":{"$error":"#REF!"}},{"$f":"SUM(B7:B37)","v":25},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},0,{"$f":"SUM(O8:O37)","v":{"$error":"#REF!"}},{"$f":"SUM(P7:P37)","v":{"$error":"#REF!"}},"%",""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD"]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(F41/F44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(H41/H44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#REF!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#REF!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":""},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#DIV/0!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":{"$error":"#REF!"}}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"D51+F51+H51+J51+L51","v":{"$error":"#REF!"}},{"$f":"E51+G51+I51+K51+M51","v":{"$error":"#REF!"}},"Nb de jours dans le mois",{"$f":"B41","v":25}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#REF!"}},{"$f":"E41/$A$41","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":{"$error":"#REF!"}},null,{"$f":"+G41+K41","v":{"$error":"#REF!"}},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":{"$error":"#REF!"}},{"$f":"+G51+K51","v":{"$error":"#REF!"}}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":{"$error":"#REF!"}}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#REF!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#REF!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":{"$error":"#REF!"}},{"$f":"SUM(E6:E11)","v":{"$error":"#REF!"}},{"$f":"SUM(D13:D18)","v":{"$error":"#REF!"}},{"$f":"SUM(E13:E18)","v":{"$error":"#REF!"}},{"$f":"SUM(D20:D25)","v":{"$error":"#REF!"}},{"$f":"SUM(E20:E25)","v":{"$error":"#REF!"}},{"$f":"SUM(D27:D32)","v":{"$error":"#REF!"}},{"$f":"SUM(E27:E32)","v":{"$error":"#REF!"}},{"$f":"SUM(D34:D39)","v":{"$error":"#REF!"}},{"$f":"SUM(E34:E39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"SUM(E65,G65,I65,K65,M65)","v":{"$error":"#REF!"}},{"$error":"#REF!"},null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":{"$error":"#REF!"}},{"$f":"SUM(G6:G11)","v":{"$error":"#REF!"}},{"$f":"SUM(F13:F18)","v":{"$error":"#REF!"}},{"$f":"SUM(G13:G18)","v":{"$error":"#REF!"}},{"$f":"SUM(F20:F25)","v":{"$error":"#REF!"}},{"$f":"SUM(G20:G25)","v":{"$error":"#REF!"}},{"$f":"SUM(F27:F32)","v":{"$error":"#REF!"}},{"$f":"SUM(G27:G32)","v":{"$error":"#REF!"}},{"$f":"SUM(F34:F39)","v":{"$error":"#REF!"}},{"$f":"SUM(G34:G39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":{"$error":"#REF!"}},{"$f":"SUM(I6:I11)","v":{"$error":"#REF!"}},{"$f":"SUM(H13:H18)","v":{"$error":"#REF!"}},{"$f":"SUM(I13:I18)","v":{"$error":"#REF!"}},{"$f":"SUM(H20:H25)","v":{"$error":"#REF!"}},{"$f":"SUM(I20:I25)","v":{"$error":"#REF!"}},{"$f":"SUM(H27:H32)","v":{"$error":"#REF!"}},{"$f":"SUM(I27:I32)","v":{"$error":"#REF!"}},{"$f":"SUM(H34:H39)","v":{"$error":"#REF!"}},{"$f":"SUM(I34:I39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":{"$error":"#REF!"}},{"$f":"SUM(K6:K11)","v":{"$error":"#REF!"}},{"$f":"SUM(J13:J18)","v":{"$error":"#REF!"}},{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},{"$f":"SUM(J20:J25)","v":{"$error":"#REF!"}},{"$f":"SUM(K20:K25)","v":{"$error":"#REF!"}},{"$f":"SUM(J27:J32)","v":{"$error":"#REF!"}},{"$f":"SUM(K27:K32)","v":{"$error":"#REF!"}},{"$f":"SUM(J34:J39)","v":{"$error":"#REF!"}},{"$f":"SUM(K34:K39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":{"$error":"#REF!"}},{"$f":"SUM(M6:M11)","v":{"$error":"#REF!"}},{"$f":"SUM(L13:L18)","v":{"$error":"#REF!"}},{"$f":"SUM(M13:M18)","v":{"$error":"#REF!"}},{"$f":"SUM(L20:L25)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M25)","v":{"$error":"#REF!"}},{"$f":"SUM(L27:L32)","v":{"$error":"#REF!"}},{"$f":"SUM(M27:M32)","v":{"$error":"#REF!"}},{"$f":"SUM(L34:L39)","v":{"$error":"#REF!"}},{"$f":"SUM(M34:M39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":{"$error":"#REF!"}},{"$f":"SUM(F66,F68)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#REF!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":{"$error":"#REF!"}},{"$f":"SUM(F65:F69)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$f":"SUM(Q65:Q69)","v":{"$error":"#REF!"}},{"$f":"SUM(R65:R69)","v":{"$error":"#REF!"}},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#REF!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#REF!"}},0.1]

{"sheet":"AOUT","index":11,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Août",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C6,1,0)","v":1},"2022-08-01",{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-08-02"},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-03",{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-04",{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-05",{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-06",{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C12+1","v":"2022-08-07"},{"$f":"IF(SUM(D7:D12)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E7:E12)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-08-08",{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$f":"SUM(E14+G14+I14+K14+M14)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-08-09",{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D15+F15+H15+J15+L15","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-10",{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D16+F16+H16+J16+L16","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-11",{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D17+F17+H17+J17+L17","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-12",{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-13",{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C19+1","v":"2022-08-14"},{"$f":"IF(SUM(D14:D19)+SUM(D7:D12)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E14:E19)+SUM(E7:E12)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[0,0,"2022-08-15"]
[{"$error":"#REF!"},1,"2022-08-16",{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-17",{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-18",{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-19",{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-20",{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C26+1","v":"2022-08-21"},{"$f":"IF(SUM(D14:D19)+SUM(D7:D12)+SUM(D21:D26)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E14:E19)+SUM(E7:E12)+SUM(E21:E26)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-08-22",{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-23",{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-24",{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-25",{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-26",{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-27",{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C33+1","v":"2022-08-28"},{"$f":"IF(SUM(D21:D26)+SUM(D14:D19)+SUM(D28:D33)+SUM(D11:D12)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E21:E26)+SUM(E14:E19)+SUM(E28:E33)+SUM(E11:E12)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-08-29",{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-30",{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-08-31",{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,{"$f":"C38+1","v":"1900-01-01"},{"$f":"IF(SUM(D28:D33)+SUM(D21:D26)+SUM(D35:D38)+SUM(D14:D19)+SUM(D7:D12)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E28:E33)+SUM(E21:E26)+SUM(E35:E38)+SUM(E14:E19)+SUM(E7:E12)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":{"$error":"#REF!"}},{"$f":"SUM(B7:B37)","v":26},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},0,{"$f":"SUM(O8:O37)","v":{"$error":"#REF!"}},{"$f":"SUM(P7:P37)","v":{"$error":"#REF!"}},"%",""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD"]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(F41/F44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(H41/H44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#REF!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#REF!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":""},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#DIV/0!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":{"$error":"#REF!"}}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"D51+F51+H51+J51+L51","v":{"$error":"#REF!"}},{"$f":"E51+G51+I51+K51+M51","v":{"$error":"#REF!"}},"Nb de jours dans le mois",{"$f":"B41","v":26}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#REF!"}},{"$f":"E41/$A$41","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":{"$error":"#REF!"}},null,{"$f":"+G41+K41","v":{"$error":"#REF!"}},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":{"$error":"#REF!"}},{"$f":"+G51+K51","v":{"$error":"#REF!"}}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":{"$error":"#REF!"}}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#REF!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#REF!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":{"$error":"#REF!"}},{"$f":"SUM(E6:E11)","v":{"$error":"#REF!"}},{"$f":"SUM(D13:D18)","v":{"$error":"#REF!"}},{"$f":"SUM(E13:E18)","v":{"$error":"#REF!"}},{"$f":"SUM(D20:D25)","v":{"$error":"#REF!"}},{"$f":"SUM(E20:E25)","v":{"$error":"#REF!"}},{"$f":"SUM(D27:D32)","v":{"$error":"#REF!"}},{"$f":"SUM(E27:E32)","v":{"$error":"#REF!"}},{"$f":"SUM(D34:D39)","v":{"$error":"#REF!"}},{"$f":"SUM(E34:E39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"SUM(E65,G65,I65,K65,M65)","v":{"$error":"#REF!"}},{"$error":"#REF!"},null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":{"$error":"#REF!"}},{"$f":"SUM(G6:G11)","v":{"$error":"#REF!"}},{"$f":"SUM(F13:F18)","v":{"$error":"#REF!"}},{"$f":"SUM(G13:G18)","v":{"$error":"#REF!"}},{"$f":"SUM(F20:F25)","v":{"$error":"#REF!"}},{"$f":"SUM(G20:G25)","v":{"$error":"#REF!"}},{"$f":"SUM(F27:F32)","v":{"$error":"#REF!"}},{"$f":"SUM(G27:G32)","v":{"$error":"#REF!"}},{"$f":"SUM(F34:F39)","v":{"$error":"#REF!"}},{"$f":"SUM(G34:G39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":{"$error":"#REF!"}},{"$f":"SUM(I6:I11)","v":{"$error":"#REF!"}},{"$f":"SUM(H13:H18)","v":{"$error":"#REF!"}},{"$f":"SUM(I13:I18)","v":{"$error":"#REF!"}},{"$f":"SUM(H20:H25)","v":{"$error":"#REF!"}},{"$f":"SUM(I20:I25)","v":{"$error":"#REF!"}},{"$f":"SUM(H27:H32)","v":{"$error":"#REF!"}},{"$f":"SUM(I27:I32)","v":{"$error":"#REF!"}},{"$f":"SUM(H34:H39)","v":{"$error":"#REF!"}},{"$f":"SUM(I34:I39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":{"$error":"#REF!"}},{"$f":"SUM(K6:K11)","v":{"$error":"#REF!"}},{"$f":"SUM(J13:J18)","v":{"$error":"#REF!"}},{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},{"$f":"SUM(J20:J25)","v":{"$error":"#REF!"}},{"$f":"SUM(K20:K25)","v":{"$error":"#REF!"}},{"$f":"SUM(J27:J32)","v":{"$error":"#REF!"}},{"$f":"SUM(K27:K32)","v":{"$error":"#REF!"}},{"$f":"SUM(J34:J39)","v":{"$error":"#REF!"}},{"$f":"SUM(K34:K39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":{"$error":"#REF!"}},{"$f":"SUM(M6:M11)","v":{"$error":"#REF!"}},{"$f":"SUM(L13:L18)","v":{"$error":"#REF!"}},{"$f":"SUM(M13:M18)","v":{"$error":"#REF!"}},{"$f":"SUM(L20:L25)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M25)","v":{"$error":"#REF!"}},{"$f":"SUM(L27:L32)","v":{"$error":"#REF!"}},{"$f":"SUM(M27:M32)","v":{"$error":"#REF!"}},{"$f":"SUM(L34:L39)","v":{"$error":"#REF!"}},{"$f":"SUM(M34:M39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":{"$error":"#REF!"}},{"$f":"SUM(F66,F68)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#REF!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":{"$error":"#REF!"}},{"$f":"SUM(F65:F69)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$f":"SUM(Q65:Q69)","v":{"$error":"#REF!"}},{"$f":"SUM(R65:R69)","v":{"$error":"#REF!"}},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#REF!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#REF!"}},0.1]

{"sheet":"SEPTEMBRE","index":12,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Septembre",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C6,1,0)","v":1},"2022-09-01",{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-09-02"},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-03",{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C9+1","v":"2022-09-04"},{"$f":"IF(SUM(D7:D9)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E7:E9)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-09-05",{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-06",{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,{"$f":"C12+1","v":"2022-09-07"},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D13+F13+H13+J13+L13","v":{"$error":"#REF!"}},{"$f":"SUM(E13+G13+I13+K13+M13)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-09-08",{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D14+F14+H14+J14+L14","v":{"$error":"#REF!"}},{"$f":"SUM(E14+G14+I14+K14+M14)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-09-09",{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D15+F15+H15+J15+L15","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-10",{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D16+F16+H16+J16+L16","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[null,null,"2022-09-11",{"$f":"IF(SUM(D11:D16)+SUM(D7:D9)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E11:E16)+SUM(E7:E9)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-09-12",{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D18+F18+H18+J18+L18","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-13",{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-14",{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-15",{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-16",{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-17",{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-09-18",{"$f":"IF(SUM(D11:D16)+SUM(D7:D9)+SUM(D18:D23)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E11:E16)+SUM(E7:E9)+SUM(E18:E23)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-09-19",{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-20",{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-21",{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-22",{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-23",{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-24",{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-09-25",{"$f":"IF(SUM(D18:D23)+SUM(D11:D16)+SUM(D25:D30)+SUM(D7:D9)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E18:E23)+SUM(E11:E16)+SUM(E25:E30)+SUM(E7:E9)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-09-26",{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-27",{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-28",{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-29",{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-09-30",{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-10-01",{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D31:D36)+SUM(D11:D16)+SUM(D7:D9)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E25:E30)+SUM(E18:E23)+SUM(E31:E36)+SUM(E11:E16)+SUM(E7:E9)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,""]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":{"$error":"#REF!"}},{"$f":"SUM(B7:B37)","v":26},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},0,{"$f":"SUM(O8:O37)","v":{"$error":"#REF!"}},{"$f":"SUM(P7:P37)","v":{"$error":"#REF!"}},"%",""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD"]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(F41/F44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(H41/H44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#REF!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#REF!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":""},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#DIV/0!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":{"$error":"#REF!"}}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"D51+F51+H51+J51+L51","v":{"$error":"#REF!"}},{"$f":"E51+G51+I51+K51+M51","v":{"$error":"#REF!"}},"Nb de jours dans le mois",{"$f":"B41","v":26}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#REF!"}},{"$f":"E41/$A$41","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":{"$error":"#REF!"}},null,{"$f":"+G41+K41","v":{"$error":"#REF!"}},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":{"$error":"#REF!"}},{"$f":"+G51+K51","v":{"$error":"#REF!"}}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":{"$error":"#REF!"}}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#REF!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#REF!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":{"$error":"#REF!"}},{"$f":"SUM(E6:E11)","v":{"$error":"#REF!"}},{"$f":"SUM(D13:D18)","v":{"$error":"#REF!"}},{"$f":"SUM(E13:E18)","v":{"$error":"#REF!"}},{"$f":"SUM(D20:D25)","v":{"$error":"#REF!"}},{"$f":"SUM(E20:E25)","v":{"$error":"#REF!"}},{"$f":"SUM(D27:D32)","v":{"$error":"#REF!"}},{"$f":"SUM(E27:E32)","v":{"$error":"#REF!"}},{"$f":"SUM(D34:D39)","v":{"$error":"#REF!"}},{"$f":"SUM(E34:E39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"SUM(E65,G65,I65,K65,M65)","v":{"$error":"#REF!"}},{"$error":"#REF!"},null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":{"$error":"#REF!"}},{"$f":"SUM(G6:G11)","v":{"$error":"#REF!"}},{"$f":"SUM(F13:F18)","v":{"$error":"#REF!"}},{"$f":"SUM(G13:G18)","v":{"$error":"#REF!"}},{"$f":"SUM(F20:F25)","v":{"$error":"#REF!"}},{"$f":"SUM(G20:G25)","v":{"$error":"#REF!"}},{"$f":"SUM(F27:F32)","v":{"$error":"#REF!"}},{"$f":"SUM(G27:G32)","v":{"$error":"#REF!"}},{"$f":"SUM(F34:F39)","v":{"$error":"#REF!"}},{"$f":"SUM(G34:G39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":{"$error":"#REF!"}},{"$f":"SUM(I6:I11)","v":{"$error":"#REF!"}},{"$f":"SUM(H13:H18)","v":{"$error":"#REF!"}},{"$f":"SUM(I13:I18)","v":{"$error":"#REF!"}},{"$f":"SUM(H20:H25)","v":{"$error":"#REF!"}},{"$f":"SUM(I20:I25)","v":{"$error":"#REF!"}},{"$f":"SUM(H27:H32)","v":{"$error":"#REF!"}},{"$f":"SUM(I27:I32)","v":{"$error":"#REF!"}},{"$f":"SUM(H34:H39)","v":{"$error":"#REF!"}},{"$f":"SUM(I34:I39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":{"$error":"#REF!"}},{"$f":"SUM(K6:K11)","v":{"$error":"#REF!"}},{"$f":"SUM(J13:J18)","v":{"$error":"#REF!"}},{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},{"$f":"SUM(J20:J25)","v":{"$error":"#REF!"}},{"$f":"SUM(K20:K25)","v":{"$error":"#REF!"}},{"$f":"SUM(J27:J32)","v":{"$error":"#REF!"}},{"$f":"SUM(K27:K32)","v":{"$error":"#REF!"}},{"$f":"SUM(J34:J39)","v":{"$error":"#REF!"}},{"$f":"SUM(K34:K39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":{"$error":"#REF!"}},{"$f":"SUM(M6:M11)","v":{"$error":"#REF!"}},{"$f":"SUM(L13:L18)","v":{"$error":"#REF!"}},{"$f":"SUM(M13:M18)","v":{"$error":"#REF!"}},{"$f":"SUM(L20:L25)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M25)","v":{"$error":"#REF!"}},{"$f":"SUM(L27:L32)","v":{"$error":"#REF!"}},{"$f":"SUM(M27:M32)","v":{"$error":"#REF!"}},{"$f":"SUM(L34:L39)","v":{"$error":"#REF!"}},{"$f":"SUM(M34:M39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":{"$error":"#REF!"}},{"$f":"SUM(F66,F68)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#REF!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":{"$error":"#REF!"}},{"$f":"SUM(F65:F69)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$f":"SUM(Q65:Q69)","v":{"$error":"#REF!"}},{"$f":"SUM(R65:R69)","v":{"$error":"#REF!"}},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#REF!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#REF!"}},0.1]

{"sheet":"OCTOBRE","index":13,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Octobre",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C6,1,0)","v":1},"2022-10-01",{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[null,null,{"$f":"C7+1","v":"2022-10-02"},{"$f":"IF(SUM(D7)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E7)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$f":"IF(O9=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C8,1,0)","v":1},{"$f":"C8+1","v":"2022-10-03"},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-04",{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-05",{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-06",{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,{"$f":"C12+1","v":"2022-10-07"},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D13+F13+H13+J13+L13","v":{"$error":"#REF!"}},{"$f":"SUM(E13+G13+I13+K13+M13)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-10-08",{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D14+F14+H14+J14+L14","v":{"$error":"#REF!"}},{"$f":"SUM(E14+G14+I14+K14+M14)","v":{"$error":"#REF!"}},"%",""]
[null,null,"2022-10-09",{"$f":"IF(SUM(D9:D14)+SUM(D7)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E9:E14)+SUM(E7)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-10-10",{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D16+F16+H16+J16+L16","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-11",{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-12",{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-13",{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-14",{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-15",{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-10-16",{"$f":"IF(SUM(D9:D14)+SUM(D7)+SUM(D16:D21)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E9:E14)+SUM(E7)+SUM(E16:E21)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-10-17",{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-18",{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,{"$f":"C24+1","v":"2022-10-19"},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-20",{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-21",{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-22",{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-10-23",{"$f":"IF(SUM(D16:D21)+SUM(D9:D14)+SUM(D23:D28)+SUM(D7)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E16:E21)+SUM(E9:E14)+SUM(E23:E28)+SUM(E7)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-10-24",{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-25",{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-26",{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-27",{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-28",{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-10-29",{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-10-30",{"$f":"IF(SUM(D23:D28)+SUM(D16:D21)+SUM(D30:D35)+SUM(D9:D14)+SUM(D7)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E23:E28)+SUM(E16:E21)+SUM(E30:E35)+SUM(E9:E14)+SUM(E7)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-10-31",{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},null,"2022-11-01",{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E25:E30)+SUM(E18:E23)+SUM(E32:E37)+SUM(E11:E16)+SUM(E4:E9)>(E42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F25:F30)+SUM(F18:F23)+SUM(F32:F37)+SUM(F11:F16)+SUM(F4:F9)>(F42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G25:G30)+SUM(G18:G23)+SUM(G32:G37)+SUM(G11:G16)+SUM(G4:G9)>(G42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF($C38=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I25:I30)+SUM(I18:I23)+SUM(I32:I37)+SUM(I11:I16)+SUM(I4:I9)>(I42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,"2022-11-02",{"$f":"IF(SUM(D23:D28)+SUM(D16:D21)+SUM(D30:D35)+SUM(D9:D14)+SUM(D7)+D37>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E23:E28)+SUM(E16:E21)+SUM(E30:E35)+SUM(E9:E14)+SUM(E7)+E37>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$f":"IF(SUM(P23:P28)+SUM(P16:P21)+SUM(P30:P35)+SUM(P9:P14)+SUM(P7)+P37>(P44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(Q23:Q28)+SUM(Q16:Q21)+SUM(Q30:Q35)+SUM(Q9:Q14)+SUM(Q7)+SUM(Q37)>(Q44*(4/$Q$2)),\"ä\",\"æ\")","v":"æ"},{"$f":"IF(SUM(R23:R28)+SUM(R16:R21)+SUM(R30:R35)+SUM(R9:R14)+SUM(R7)+SUM(R37)>(R44*(4/$Q$2)),\"ä\",\"æ\")","v":"æ"}]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":{"$error":"#REF!"}},{"$f":"SUM(B7:B37)","v":26},"TOTAL MTD",{"$f":"SUM(D7:D35)","v":{"$error":"#REF!"}},{"$f":"SUM(E7:E35)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},0,{"$error":"#REF!"},{"$error":"#REF!"},0,0]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD"]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(F41/F44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(H41/H44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#REF!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#REF!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":0},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":0}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#DIV/0!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":{"$error":"#REF!"}}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"D51+F51+H51+J51+L51","v":{"$error":"#REF!"}},{"$f":"E51+G51+I51+K51+M51","v":{"$error":"#REF!"}},"Nb de jours dans le mois",{"$f":"B41","v":26}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#REF!"}},{"$f":"E41/$A$41","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":{"$error":"#REF!"}},null,{"$f":"+G41+K41","v":{"$error":"#REF!"}},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":{"$error":"#REF!"}},{"$f":"+G51+K51","v":{"$error":"#REF!"}}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":{"$error":"#REF!"}}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#REF!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#REF!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":{"$error":"#REF!"}},{"$f":"SUM(E6:E11)","v":{"$error":"#REF!"}},{"$f":"SUM(D13:D18)","v":{"$error":"#REF!"}},{"$f":"SUM(E13:E18)","v":{"$error":"#REF!"}},{"$f":"SUM(D20:D25)","v":{"$error":"#REF!"}},{"$f":"SUM(E20:E25)","v":{"$error":"#REF!"}},{"$f":"SUM(D27:D32)","v":{"$error":"#REF!"}},{"$f":"SUM(E27:E32)","v":{"$error":"#REF!"}},{"$f":"SUM(D34:D39)","v":{"$error":"#REF!"}},{"$f":"SUM(E34:E39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"SUM(E65,G65,I65,K65,M65)","v":{"$error":"#REF!"}},{"$error":"#REF!"},null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":{"$error":"#REF!"}},{"$f":"SUM(G6:G11)","v":{"$error":"#REF!"}},{"$f":"SUM(F13:F18)","v":{"$error":"#REF!"}},{"$f":"SUM(G13:G18)","v":{"$error":"#REF!"}},{"$f":"SUM(F20:F25)","v":{"$error":"#REF!"}},{"$f":"SUM(G20:G25)","v":{"$error":"#REF!"}},{"$f":"SUM(F27:F32)","v":{"$error":"#REF!"}},{"$f":"SUM(G27:G32)","v":{"$error":"#REF!"}},{"$f":"SUM(F34:F39)","v":{"$error":"#REF!"}},{"$f":"SUM(G34:G39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":{"$error":"#REF!"}},{"$f":"SUM(I6:I11)","v":{"$error":"#REF!"}},{"$f":"SUM(H13:H18)","v":{"$error":"#REF!"}},{"$f":"SUM(I13:I18)","v":{"$error":"#REF!"}},{"$f":"SUM(H20:H25)","v":{"$error":"#REF!"}},{"$f":"SUM(I20:I25)","v":{"$error":"#REF!"}},{"$f":"SUM(H27:H32)","v":{"$error":"#REF!"}},{"$f":"SUM(I27:I32)","v":{"$error":"#REF!"}},{"$f":"SUM(H34:H39)","v":{"$error":"#REF!"}},{"$f":"SUM(I34:I39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":{"$error":"#REF!"}},{"$f":"SUM(K6:K11)","v":{"$error":"#REF!"}},{"$f":"SUM(J13:J18)","v":{"$error":"#REF!"}},{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},{"$f":"SUM(J20:J25)","v":{"$error":"#REF!"}},{"$f":"SUM(K20:K25)","v":{"$error":"#REF!"}},{"$f":"SUM(J27:J32)","v":{"$error":"#REF!"}},{"$f":"SUM(K27:K32)","v":{"$error":"#REF!"}},{"$f":"SUM(J34:J39)","v":{"$error":"#REF!"}},{"$f":"SUM(K34:K39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":{"$error":"#REF!"}},{"$f":"SUM(M6:M11)","v":{"$error":"#REF!"}},{"$f":"SUM(L13:L18)","v":{"$error":"#REF!"}},{"$f":"SUM(M13:M18)","v":{"$error":"#REF!"}},{"$f":"SUM(L20:L25)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M25)","v":{"$error":"#REF!"}},{"$f":"SUM(L27:L32)","v":{"$error":"#REF!"}},{"$f":"SUM(M27:M32)","v":{"$error":"#REF!"}},{"$f":"SUM(L34:L39)","v":{"$error":"#REF!"}},{"$f":"SUM(M34:M39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":{"$error":"#REF!"}},{"$f":"SUM(F66,F68)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#REF!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":{"$error":"#REF!"}},{"$f":"SUM(F65:F69)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$f":"SUM(Q65:Q69)","v":{"$error":"#REF!"}},{"$f":"SUM(R65:R69)","v":{"$error":"#REF!"}},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#REF!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#REF!"}},0.1]

{"sheet":"NOVEMBRE","index":14,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Novembre",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C6,1,0)","v":1},"2022-11-01",{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-11-02"},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-03",{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-04",{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C10=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-05",{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C11+1","v":"2022-11-06"},{"$f":"IF(SUM(D7:D11)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E7:E11)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,{"$f":"C12+1","v":"2022-11-07"},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D13+F13+H13+J13+L13","v":{"$error":"#REF!"}},{"$f":"SUM(E13+G13+I13+K13+M13)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-11-08",{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D14+F14+H14+J14+L14","v":{"$error":"#REF!"}},{"$f":"SUM(E14+G14+I14+K14+M14)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-11-09",{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D15+F15+H15+J15+L15","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-10",{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D16+F16+H16+J16+L16","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-11",{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C17=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D17+F17+H17+J17+L17","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-12",{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D18+F18+H18+J18+L18","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[null,null,"2022-11-13",{"$f":"IF(SUM(D13:D18)+SUM(D7:D11)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E13:E18)+SUM(E7:E11)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-11-14",{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-15",{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-16",{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-17",{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-18",{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C24=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-19",{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-11-20",{"$f":"IF(SUM(D13:D18)+SUM(D7:D11)+SUM(D20:D25)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E13:E18)+SUM(E7:E11)+SUM(E20:E25)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-11-21",{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-22",{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-23",{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-24",{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-25",{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C31=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-26",{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-11-27",{"$f":"IF(SUM(D20:D25)+SUM(D13:D18)+SUM(D27:D32)+SUM(D7:D11)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E20:E25)+SUM(E13:E18)+SUM(E27:E32)+SUM(E7:E11)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-11-28",{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-29",{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-11-30",{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-12-01",{"$f":"IF(SUM(D27:D32)+SUM(D20:D25)+SUM(D34:D36)+SUM(D13:D18)+SUM(D7:D9)+SUM(D10:D11)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E27:E32)+SUM(E20:E25)+SUM(E34:E36)+SUM(E13:E18)+SUM(E7:E9)+SUM(E10:E11)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,""]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":{"$error":"#REF!"}},{"$f":"SUM(B7:B37)","v":26},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},0,{"$f":"SUM(O8:O37)","v":{"$error":"#REF!"}},{"$f":"SUM(P7:P37)","v":{"$error":"#REF!"}},"%",""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD"]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(F41/F44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(H41/H44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#REF!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#REF!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":""},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#DIV/0!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":{"$error":"#REF!"}}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"D51+F51+H51+J51+L51","v":{"$error":"#REF!"}},{"$f":"E51+G51+I51+K51+M51","v":{"$error":"#REF!"}},"Nb de jours dans le mois",{"$f":"B41","v":26}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#REF!"}},{"$f":"E41/$A$41","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":{"$error":"#REF!"}},null,{"$f":"+G41+K41","v":{"$error":"#REF!"}},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":{"$error":"#REF!"}},{"$f":"+G51+K51","v":{"$error":"#REF!"}}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":{"$error":"#REF!"}}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#REF!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#REF!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":{"$error":"#REF!"}},{"$f":"SUM(E6:E11)","v":{"$error":"#REF!"}},{"$f":"SUM(D13:D18)","v":{"$error":"#REF!"}},{"$f":"SUM(E13:E18)","v":{"$error":"#REF!"}},{"$f":"SUM(D20:D25)","v":{"$error":"#REF!"}},{"$f":"SUM(E20:E25)","v":{"$error":"#REF!"}},{"$f":"SUM(D27:D32)","v":{"$error":"#REF!"}},{"$f":"SUM(E27:E32)","v":{"$error":"#REF!"}},{"$f":"SUM(D34:D39)","v":{"$error":"#REF!"}},{"$f":"SUM(E34:E39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"SUM(E65,G65,I65,K65,M65)","v":{"$error":"#REF!"}},{"$error":"#REF!"},null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":{"$error":"#REF!"}},{"$f":"SUM(G6:G11)","v":{"$error":"#REF!"}},{"$f":"SUM(F13:F18)","v":{"$error":"#REF!"}},{"$f":"SUM(G13:G18)","v":{"$error":"#REF!"}},{"$f":"SUM(F20:F25)","v":{"$error":"#REF!"}},{"$f":"SUM(G20:G25)","v":{"$error":"#REF!"}},{"$f":"SUM(F27:F32)","v":{"$error":"#REF!"}},{"$f":"SUM(G27:G32)","v":{"$error":"#REF!"}},{"$f":"SUM(F34:F39)","v":{"$error":"#REF!"}},{"$f":"SUM(G34:G39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":{"$error":"#REF!"}},{"$f":"SUM(I6:I11)","v":{"$error":"#REF!"}},{"$f":"SUM(H13:H18)","v":{"$error":"#REF!"}},{"$f":"SUM(I13:I18)","v":{"$error":"#REF!"}},{"$f":"SUM(H20:H25)","v":{"$error":"#REF!"}},{"$f":"SUM(I20:I25)","v":{"$error":"#REF!"}},{"$f":"SUM(H27:H32)","v":{"$error":"#REF!"}},{"$f":"SUM(I27:I32)","v":{"$error":"#REF!"}},{"$f":"SUM(H34:H39)","v":{"$error":"#REF!"}},{"$f":"SUM(I34:I39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":{"$error":"#REF!"}},{"$f":"SUM(K6:K11)","v":{"$error":"#REF!"}},{"$f":"SUM(J13:J18)","v":{"$error":"#REF!"}},{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},{"$f":"SUM(J20:J25)","v":{"$error":"#REF!"}},{"$f":"SUM(K20:K25)","v":{"$error":"#REF!"}},{"$f":"SUM(J27:J32)","v":{"$error":"#REF!"}},{"$f":"SUM(K27:K32)","v":{"$error":"#REF!"}},{"$f":"SUM(J34:J39)","v":{"$error":"#REF!"}},{"$f":"SUM(K34:K39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":{"$error":"#REF!"}},{"$f":"SUM(M6:M11)","v":{"$error":"#REF!"}},{"$f":"SUM(L13:L18)","v":{"$error":"#REF!"}},{"$f":"SUM(M13:M18)","v":{"$error":"#REF!"}},{"$f":"SUM(L20:L25)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M25)","v":{"$error":"#REF!"}},{"$f":"SUM(L27:L32)","v":{"$error":"#REF!"}},{"$f":"SUM(M27:M32)","v":{"$error":"#REF!"}},{"$f":"SUM(L34:L39)","v":{"$error":"#REF!"}},{"$f":"SUM(M34:M39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":{"$error":"#REF!"}},{"$f":"SUM(F66,F68)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#REF!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":{"$error":"#REF!"}},{"$f":"SUM(F65:F69)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$f":"SUM(Q65:Q69)","v":{"$error":"#REF!"}},{"$f":"SUM(R65:R69)","v":{"$error":"#REF!"}},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#REF!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#REF!"}},0.1]

{"sheet":"DECEMBRE","index":15,"n_rows":72,"n_cols":36,"rows_kept":72,"cut":false,"hidden":false,"merged":[[24,19,24,21],[1,5,1,10],[1,11,1,13],[1,14,1,15],[3,3,3,4],[3,5,3,6],[3,7,3,8],[3,9,3,10],[3,11,3,12],[3,13,4,13],[3,14,4,14],[3,15,4,15],[3,16,4,16],[3,17,4,17],[6,19,6,21],[15,19,15,21],[42,3,42,4],[42,5,42,6],[42,7,42,8],[42,9,42,10],[42,11,42,12],[25,20,25,21],[26,20,26,21],[27,20,27,21],[28,20,28,21],[30,19,30,21],[49,3,49,4],[49,5,49,6],[49,7,49,8],[49,9,49,10],[49,11,49,12],[52,3,52,12],[52,16,52,17],[54,4,54,5],[54,6,54,7],[55,4,55,5],[55,6,55,7],[56,4,56,5],[56,6,56,7],[56,9,57,9],[56,10,57,10],[56,11,57,11],[57,4,57,5],[57,6,57,7],[58,4,58,5],[58,6,58,7],[59,4,59,5],[59,6,59,7],[62,4,62,5],[62,6,62,7],[62,29,62,30],[62,31,62,32],[62,8,62,9],[62,10,62,11],[62,12,62,13],[62,14,62,15],[62,16,62,17],[62,24,62,27]]}
[]
[null,null,null,null,null,null,null,null,null,null,null,"Décembre",null,null,2022,null,4]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"C",null,"TRANSAC           JOUR","CA             JOUR","IMU                     JOUR","% IMU","PM   JOUR"]
[null,null,null,"CA","IMU","CA","IMU","CA","IMU","CA","IMU","CA","IMU"]
[null,null,"2022-02-28",0,0,0,0,0,0,0,0,0,0,0,{"$f":"D6+F6+H6+J6+L6","v":0},{"$f":"SUM(E6+G6+I6+K6+M6)","v":0},{"$f":"IF(ISERROR(P6/O6),\"%\",P6/O6)","v":"%"},{"$f":"IF(N6=0,\"\",O6/N6)","v":""}]
[{"$f":"IF(O7=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C6,1,0)","v":1},"2022-12-01",{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C7=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",{"$f":"IF(N7=0,\"\",O7/N7)","v":""}]
[{"$f":"IF(O8=0,0,1)","v":{"$error":"#REF!"}},{"$f":"IF(C7,1,0)","v":1},{"$f":"C7+1","v":"2022-12-02"},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C8=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-03",{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C9=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,{"$f":"C9+1","v":"2022-12-04"},{"$f":"IF(SUM(D7:D9)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E7:E9)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-12-05",{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C11=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-06",{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C12=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,{"$f":"C12+1","v":"2022-12-07"},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C13=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D13+F13+H13+J13+L13","v":{"$error":"#REF!"}},{"$f":"SUM(E13+G13+I13+K13+M13)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-12-08",{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C14=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D14+F14+H14+J14+L14","v":{"$error":"#REF!"}},{"$f":"SUM(E14+G14+I14+K14+M14)","v":{"$error":"#REF!"}},"%",""]
[{"$error":"#REF!"},1,"2022-12-09",{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C15=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D15+F15+H15+J15+L15","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-10",{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C16=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D16+F16+H16+J16+L16","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[null,null,"2022-12-11",{"$f":"IF(SUM(D11:D16)+SUM(D7:D9)>(D44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E11:E16)+SUM(E7:E9)>(E44*(1/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-12-12",{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C18=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$f":"D18+F18+H18+J18+L18","v":{"$error":"#REF!"}},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-13",{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C19=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-14",{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C20=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-15",{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C21=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-16",{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C22=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-17",{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C23=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-12-18",{"$f":"IF(SUM(D11:D16)+SUM(D7:D9)+SUM(D18:D23)>(D44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E11:E16)+SUM(E7:E9)+SUM(E18:E23)>(E44*(2/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-12-19",{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C25=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-20",{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C26=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-21",{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C27=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-22",{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C28=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-23",{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C29=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-24",{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C30=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,"2022-12-25",{"$f":"IF(SUM(D18:D23)+SUM(D11:D16)+SUM(D25:D30)+SUM(D7:D9)>(D44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E18:E23)+SUM(E11:E16)+SUM(E25:E30)+SUM(E7:E9)>(E44*(3/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[{"$error":"#REF!"},1,"2022-12-26",{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C32=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-27",{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C33=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-28",{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C34=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-29",{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C35=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-30",{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C36=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[{"$error":"#REF!"},1,"2022-12-31",{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},{"$f":"IF($C37=#REF!,#REF!,\"0\")","v":{"$error":"#REF!"}},0,{"$error":"#REF!"},{"$error":"#REF!"},"%",""]
[null,null,null,{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D37)+SUM(D11:D16)+SUM(D4:D9)>(D42),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[null,null,"1900-01-01",{"$f":"IF(SUM(D25:D30)+SUM(D18:D23)+SUM(D32:D38)+SUM(D11:D16)+SUM(D7:D9)>(D44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E25:E30)+SUM(E18:E23)+SUM(E32:E38)+SUM(E11:E16)+SUM(E7:E9)>(E44*(4/$Q$2)),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"æ",{"$error":"#REF!"},{"$error":"#REF!"},"æ","æ"]
[]
[{"$f":"SUM(A34:A37,A27:A32,A20:A25,A13:A18,A7:A11)","v":{"$error":"#REF!"}},{"$f":"SUM(B7:B37)","v":27},"TOTAL MTD",{"$f":"SUM(D7:D37)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},0,{"$f":"SUM(O8:O37)","v":{"$error":"#REF!"}},{"$f":"SUM(P7:P37)","v":{"$error":"#REF!"}},"%",""]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","IMU","% IMU","PM"]
[null,null,"OBJECTIF MTD"]
[null,null,"INDEX (vs AOP)",{"$f":"IF(D52>(D44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E52>(E44/$B$41),\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"IF(Q41>Q44,\"ä\",\"æ\")","v":"ä"},{"$f":"IF(R41>R44,\"ä\",\"æ\")","v":"æ"}]
[null,null,"% RÉALISÉ",{"$f":"SUM(D41/D44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(F41/F44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$f":"SUM(H41/H44)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"SUM(N41/N44)","v":{"$error":"#DIV/0!"}},{"$f":"(D41+F41+H41+J41+L41)/O44","v":{"$error":"#REF!"}},{"$f":"(E41+G41+I41+K41+M41)/P44","v":{"$error":"#REF!"}},{"$f":"IF(ISERROR(Q41-Q44),\"\",Q41-Q44)","v":""},{"$f":"IF(ISERROR(R41-R44),\"\",R41-R44)","v":""}]
[null,null,"INDEX (vs % Réal Attendu)",{"$f":"IF(D46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(E46>$Q$53,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#DIV/0!"},{"$error":"#REF!"},{"$error":"#REF!"}]
[]
[]
[null,null,null,"MO",null,"B",null,"F",null,"MI",null,"I",null,"TX","CA","MARGE","Nb de Jours restants mois",{"$f":"+$R$51-$A$41","v":{"$error":"#REF!"}}]
[null,null,"CA/MGE/TR Restants à faire/ jour",{"$f":"IF($R$50=0,D44-D41,(D44-D41)/$R$50)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$f":"D51+F51+H51+J51+L51","v":{"$error":"#REF!"}},{"$f":"E51+G51+I51+K51+M51","v":{"$error":"#REF!"}},"Nb de jours dans le mois",{"$f":"B41","v":27}]
[null,null,null,{"$f":"D41/$A$41","v":{"$error":"#REF!"}},{"$f":"E41/$A$41","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},"               % Réalisation Attendu "]
[null,null,null,"PÔLE ",null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"((100/$R$51)*($R$51-$R$50))/100","v":{"$error":"#REF!"}}]
[]
[null,null,null,null,"CA",null,"IMU"]
[null,null,null,"OBJECTIF MTD",{"$f":"+F44+J44","v":0},null,{"$f":"+G44+K44","v":0},null,"²",null,"CA","IMU"]
[null,null,null,"Réalisé MTD",{"$f":"+F41+J41","v":{"$error":"#REF!"}},null,{"$f":"+G41+K41","v":{"$error":"#REF!"}},null,null,"CA/MGE    Restants à faire/jour",{"$f":"+F51+J51","v":{"$error":"#REF!"}},{"$f":"+G51+K51","v":{"$error":"#REF!"}}]
[null,null,null,"INDEX",{"$f":"IF(E57>E60,\"ä\",\"æ\")","v":{"$error":"#REF!"}},{"$f":"IF(F54>F61,\"ä\",\"æ\")","v":"æ"},{"$f":"IF(G57>G60,\"ä\",\"æ\")","v":{"$error":"#REF!"}}]
[null,null,null,"% RÉALISÉ",{"$f":"+$E$57/$E$56","v":{"$error":"#REF!"}},null,{"$f":"+$G$57/$G$56","v":{"$error":"#REF!"}}]
[null,null,null,null,{"$f":"(E56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}},null,{"$f":"(G56/$R$51)*($R$51-$R$50)","v":{"$error":"#REF!"}}]
[]
[]
[null,null,null,null,"S1",null,"S2",null,"S3",null,"S4",null,"S5",null,"CONTRÔLE",null,"TOTAL DIVISIONS",null,null,null,null,null,null,null,"AOP  DIVISIONS",null,null,null,null,"Delta VS Prime T2",null,"Delta VS Prime T300"]
[null,null,null,null,"CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE","CA","MARGE",null,null,null,null,null,null,"CA","MARGE","CA/Sem","Marge/Sem",null,"CA(85%)","MARGE (90%)","CA (95%)","MARGE (95%)"]
[{"$f":"D65","v":"MOBILIER"},null,1,"MOBILIER",{"$f":"SUM(D6:D11)","v":{"$error":"#REF!"}},{"$f":"SUM(E6:E11)","v":{"$error":"#REF!"}},{"$f":"SUM(D13:D18)","v":{"$error":"#REF!"}},{"$f":"SUM(E13:E18)","v":{"$error":"#REF!"}},{"$f":"SUM(D20:D25)","v":{"$error":"#REF!"}},{"$f":"SUM(E20:E25)","v":{"$error":"#REF!"}},{"$f":"SUM(D27:D32)","v":{"$error":"#REF!"}},{"$f":"SUM(E27:E32)","v":{"$error":"#REF!"}},{"$f":"SUM(D34:D39)","v":{"$error":"#REF!"}},{"$f":"SUM(E34:E39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E65,G65,I65,K65,M65)=D41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65,H65,J65,L65,N65)=E41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"SUM(E65,G65,I65,K65,M65)","v":{"$error":"#REF!"}},{"$error":"#REF!"},null,null,null,null,null,"MOBILIER",{"$f":"+D44","v":0},{"$f":"+E44","v":0},{"$f":"Y65/$Q$2","v":0},{"$f":"Z65/$Q$2","v":0},"MOB",{"$f":"Y65*85%","v":0},{"$f":"Z65*90%","v":0}]
[{"$f":"D66","v":"BUREAUTIQUE"},null,2,"BUREAUTIQUE",{"$f":"SUM(F6:F11)","v":{"$error":"#REF!"}},{"$f":"SUM(G6:G11)","v":{"$error":"#REF!"}},{"$f":"SUM(F13:F18)","v":{"$error":"#REF!"}},{"$f":"SUM(G13:G18)","v":{"$error":"#REF!"}},{"$f":"SUM(F20:F25)","v":{"$error":"#REF!"}},{"$f":"SUM(G20:G25)","v":{"$error":"#REF!"}},{"$f":"SUM(F27:F32)","v":{"$error":"#REF!"}},{"$f":"SUM(G27:G32)","v":{"$error":"#REF!"}},{"$f":"SUM(F34:F39)","v":{"$error":"#REF!"}},{"$f":"SUM(G34:G39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E66,G66,I66,K66,M66)=F41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F66,H66,J66,L66,N66)=G41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"BUREAUTIQUE",{"$f":"+F44","v":0},{"$f":"+G44","v":0},{"$f":"Y66/$Q$2","v":0},0,"BUR",0,0]
["FOURNITURES",null,3,"FOURNITURES",{"$f":"SUM(H6:H11)","v":{"$error":"#REF!"}},{"$f":"SUM(I6:I11)","v":{"$error":"#REF!"}},{"$f":"SUM(H13:H18)","v":{"$error":"#REF!"}},{"$f":"SUM(I13:I18)","v":{"$error":"#REF!"}},{"$f":"SUM(H20:H25)","v":{"$error":"#REF!"}},{"$f":"SUM(I20:I25)","v":{"$error":"#REF!"}},{"$f":"SUM(H27:H32)","v":{"$error":"#REF!"}},{"$f":"SUM(I27:I32)","v":{"$error":"#REF!"}},{"$f":"SUM(H34:H39)","v":{"$error":"#REF!"}},{"$f":"SUM(I34:I39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E67,G67,I67,K67,M67)=H41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F67,H67,J67,L67,N67)=I41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"FOURNITURES",{"$f":"+H44","v":0},{"$f":"+I44","v":0},0,0,"FOURN",0,0]
["MICRO",null,4,"MICRO",{"$f":"SUM(J6:J11)","v":{"$error":"#REF!"}},{"$f":"SUM(K6:K11)","v":{"$error":"#REF!"}},{"$f":"SUM(J13:J18)","v":{"$error":"#REF!"}},{"$f":"SUM(K13:K18)","v":{"$error":"#REF!"}},{"$f":"SUM(J20:J25)","v":{"$error":"#REF!"}},{"$f":"SUM(K20:K25)","v":{"$error":"#REF!"}},{"$f":"SUM(J27:J32)","v":{"$error":"#REF!"}},{"$f":"SUM(K27:K32)","v":{"$error":"#REF!"}},{"$f":"SUM(J34:J39)","v":{"$error":"#REF!"}},{"$f":"SUM(K34:K39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E68,G68,I68,K68,M68)=J41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F68,H68,J68,L68,N68)=K41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"MICRO",{"$f":"+J44","v":0},{"$f":"+K44","v":0},0,0,"MICRO",0,0]
["COPIE IMPRIMERIE",null,9,"COPIE IMPRIMERIE",{"$f":"SUM(L6:L11)","v":{"$error":"#REF!"}},{"$f":"SUM(M6:M11)","v":{"$error":"#REF!"}},{"$f":"SUM(L13:L18)","v":{"$error":"#REF!"}},{"$f":"SUM(M13:M18)","v":{"$error":"#REF!"}},{"$f":"SUM(L20:L25)","v":{"$error":"#REF!"}},{"$f":"SUM(M20:M25)","v":{"$error":"#REF!"}},{"$f":"SUM(L27:L32)","v":{"$error":"#REF!"}},{"$f":"SUM(M27:M32)","v":{"$error":"#REF!"}},{"$f":"SUM(L34:L39)","v":{"$error":"#REF!"}},{"$f":"SUM(M34:M39)","v":{"$error":"#REF!"}},{"$f":"IF(SUM(E69,G69,I69,K69,M69)=L41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F69,H69,J69,L69,N69)=M41,\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"COPIE IMPRIMERIE",{"$f":"+L44","v":0},{"$f":"+M44","v":0},0,0,"IMAG",0,0,null,null,null,"PDM Imag"]
["Pôle Techno",null,"2&4","Pôle Techno",{"$f":"SUM(E66,E68)","v":{"$error":"#REF!"}},{"$f":"SUM(F66,F68)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$error":"#REF!"},{"$error":"#REF!"},null,null,null,null,null,"Pôle Techno",{"$f":"+Y66+Y68","v":0},{"$f":"+Z66+Z68","v":0},0,0,null,0,0,null,null,null,{"$f":"+Q69/Q71","v":{"$error":"#REF!"}}]
["MAGASIN",null,null,"MAGASIN",{"$f":"SUM(E65:E69)","v":{"$error":"#REF!"}},{"$f":"SUM(F65:F69)","v":{"$error":"#REF!"}},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},{"$error":"#REF!"},null,null,{"$f":"SUM(Q65:Q69)","v":{"$error":"#REF!"}},{"$f":"SUM(R65:R69)","v":{"$error":"#REF!"}},null,null,null,null,null,"MAGASIN",{"$f":"SUM(Y65:Y69)","v":0},{"$f":"SUM(Z65:Z69)","v":0},0,0,null,null,null,{"$f":"Y71*95%","v":0},{"$f":"Z71*95%","v":0},"OD",{"$f":"IF(AND($AI$70>=4%,$AI$70<5%),25,IF($AI$70>=5%,50,0))","v":{"$error":"#REF!"}},0.05]
[null,null,null,"CONTRÔLE",{"$f":"IF(SUM(E65:E69)=SUM(O6:O11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(F65:F69)=SUM(P6:P11),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(G65:G69)=SUM(O13:O18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(H65:H69)=SUM(P13:P18),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(I65:I69)=SUM(O20:O25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(J65:J69)=SUM(P20:P25),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(K65:K69)=SUM(O27:O32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(L65:L69)=SUM(P27:P32),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(M65:M69)=SUM(O34:O39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},{"$f":"IF(SUM(N65:N69)=SUM(P34:P39),\"OK\",\"NOK\")","v":{"$error":"#REF!"}},null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"ODC",{"$f":"IF(AND($AI$70>=9%,$AI$70<10%),25,IF($AI$70>=10%,50,0))","v":{"$error":"#REF!"}},0.1]